{"id":61112,"date":"2022-07-02T15:10:17","date_gmt":"2022-07-02T13:10:17","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/"},"modified":"2026-03-14T02:30:29","modified_gmt":"2026-03-14T01:30:29","slug":"esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/","title":{"rendered":"esploratori e esplorazioni"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione della Societ&agrave; Editrice Internazionale (SEI) del 1970 in ottimo stato di conservazione, collana &ldquo;Apollo 11&rdquo; Serie Storica. <\/strong><strong>In-8, legatura editoriale telata rossa con stampa in nero al piatto anteriore e al dorso; sovraccoperta in carta (ingiallita e usurata ai tagli e al dorso) illustrata a colori con alette (aletta posteriore tagliata all&#8217;angolo inferiore); 200 pp., con dedica a penna e numerose tavole fotografiche in nero e a colori fuori testo.<\/strong><\/p>\n<p>Dall&#8217;introduzione: <em>[..] Il mito di Ulisse, collegato con la guerra di Troia, &egrave; situato alla fine del XII secolo a. C., ma ben prima di allora, navigatori cretesi e viaggiatori egiziani, persiani, fenici, mesopotamici, avevano battuto le vie terrestri e marittime del vicino e pi&ugrave; lontano Oriente.<\/em><\/p>\n<p><em>Le Colonne d&#8217;Ercole erano una specie di porta vietata nel senso est-ovest, al di l&agrave; delle quali non si poteva andare; e le correnti che partivano dal capo Boiador e rendevano estremamente difficoltoso il passaggio dal Mediterraneo all&#8217;Atlantico, avvaloravano il mito del passaggio vietato.<\/em><\/p>\n<p><em>Scrittori greci e romani hanno descritto imprese mirabolanti di alcuni audaci, ma in genere le popolazioni che pi&ugrave; di altre hanno dimostrato desiderio di espansione e spirito di iniziativa nell&#8217;allontanarsi dalle loro sedi naturali, hanno compiuto le loro imprese per motivi religiosi o, pi&ugrave; frequentemente, per motivi commerciali, talvolta per via mare, il pi&ugrave; spesso con lunghi e tortuosi viaggi terrestri.<\/em><\/p>\n<p><em>Tra i popoli che hanno pi&ugrave; degli altri manifestato praticamente e con continuit&agrave; la loro tendenza a viaggiare, sono stati i Fenici a sud e i Vichinghi o Normanni a nord. Qualunque siano state le loro imprese, delle quali di occuperemo diffusamente fra breve, siamo lontani dal principio che informa l&#8217;ultimo viaggio di Ulisse narrato da Dante; viaggio che esulava, come abbiamo detto, da ogni scopo pratico e considerava il solo principio del sapere per il sapere, del conoscere per il conoscere: lo stesso spirito che ha spinto gli uomini a varcare non gi&agrave; le Colonne d&#8217;Ercole, ma i confini dell&#8217;atmosfera terrestre e spingersi nel cosmo.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>folco quilici &#8211; maria quilici<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>societ\u00e0 editrice internazionale (sei)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1656767416<\/p>\n","protected":false},"featured_media":141697,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3013,2608],"product_tag":[],"class_list":{"0":"post-61112","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-everything-else-books-navigation-history-exploration","7":"product_cat-reports-and-essays","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>esploratori e esplorazioni - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"esploratori e esplorazioni\" \/>\n<meta property=\"og:description\" content=\"Author: folco quilici - maria quiliciPublisher: societ\u00e0 editrice internazionale (sei)ISBN: LDM1656767416\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:30:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-societa-editrice-internazionale-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"505\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\\\/\",\"name\":\"esploratori e esplorazioni - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-societa-editrice-internazionale-4.jpg\",\"datePublished\":\"2022-07-02T13:10:17+00:00\",\"dateModified\":\"2026-03-14T01:30:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-societa-editrice-internazionale-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-societa-editrice-internazionale-4.jpg\",\"width\":505,\"height\":749},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"esploratori e esplorazioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1656767416\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"esploratori e esplorazioni - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"esploratori e esplorazioni","og_description":"Author: folco quilici - maria quiliciPublisher: societ\u00e0 editrice internazionale (sei)ISBN: LDM1656767416","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:30:29+00:00","og_image":[{"width":505,"height":749,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-societa-editrice-internazionale-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/","name":"esploratori e esplorazioni - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-societa-editrice-internazionale-4.jpg","datePublished":"2022-07-02T13:10:17+00:00","dateModified":"2026-03-14T01:30:29+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-societa-editrice-internazionale-4.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-societa-editrice-internazionale-4.jpg","width":505,"height":749},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-ldm1656767416\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"esploratori e esplorazioni"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1656767416","product_condition":"new"},"df_price":19,"df_sale_price":"","df_regular_price":19,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/esploratori-e-esplorazioni-folco-quilici-maria-quilici-societa-editrice-internazionale-4-202x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/61112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=61112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/141697"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=61112"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=61112"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=61112"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=61112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}