{"id":60969,"date":"2022-06-30T15:53:22","date_gmt":"2022-06-30T13:53:22","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/"},"modified":"2026-03-14T02:31:26","modified_gmt":"2026-03-14T01:31:26","slug":"un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/","title":{"rendered":"un vagabondo dei mari del sud"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione del Gruppo Ugo Mursia Editore del 2000 in ottimo stato di conservazione, collana &#8220;Quelli di Capo Horn&#8221; 11. In-8, brossura illustrata a colori con alette; 320 pp.; con antiporta e frontespizio illustrati in nero e alcune illustrazioni in nero nel testo.<\/strong><\/p>\n<p><strong>Traduzione dal francese e introduzione di Francesco Di Franco.<\/strong><\/p>\n<p>Dall&#8217;aletta anteriore:&nbsp;<em>Per unanime riconoscimento, questo &egrave; uno dei pi&ugrave; bei libri di mare che siano mai stati scritti. E anche uno dei pi&ugrave; singolari.<\/em><\/p>\n<p><em>Partito da Singapore con la sua giunca&nbsp;<\/em>Marie-Th&eacute;r&egrave;se<em>, nel 1952, Moitessier affront&ograve; in navigazione solitaria il Monsone dell&#8217;Oceano Indiano, finendo sugli scogli nel gruppo delle Chagos. All&#8217;isola Maurizio riusc&igrave; poi a guadagnarsi da vivere, sia pure rischiosamente, e a costruire con le proprie mani il <\/em>Marie-Th&eacute;r&egrave;se&nbsp;II<em>, che doveva portarlo, risalito l&#8217;Atlantico, fino a Trinidad. Fu nel Mare delle Antille che Moitessier &ndash; per una banale disattenzione, ma non senza provare in seguito un profondo e tenace senso di colpa &ndash; perse anche questa barca.<\/em><\/p>\n<p><em>Da allora Moitessier ha passato Capo Horn un paio di volte e ha fatto il giro del mondo in solitario senza scalo, ma nessuna esperienza &egrave; stata rivelatrice e <\/em>di scoperta<em>&nbsp;come la lunga avventura narrata in queste pagine: scoperta tecnica vissuta a contatto con la barca, e scoperta di un modo di vivere, libero dalle pastoie della vita sociale, ma soggetto esclusivamente alla disciplina del mare.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>bernard moitessier<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1656597201<\/p>\n","protected":false},"featured_media":122139,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805,2607],"product_tag":[],"class_list":{"0":"post-60969","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","7":"product_cat-narrative","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>un vagabondo dei mari del sud - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"un vagabondo dei mari del sud\" \/>\n<meta property=\"og:description\" content=\"Author: bernard moitessierPublisher: Ugo Mursia EditoreISBN: LDM1656597201\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:31:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-mursia-quelli-di-capo-horn-2000-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"510\" \/>\n\t<meta property=\"og:image:height\" content=\"757\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;10,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\\\/\",\"name\":\"un vagabondo dei mari del sud - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-mursia-quelli-di-capo-horn-2000-3.jpg\",\"datePublished\":\"2022-06-30T13:53:22+00:00\",\"dateModified\":\"2026-03-14T01:31:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-mursia-quelli-di-capo-horn-2000-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-mursia-quelli-di-capo-horn-2000-3.jpg\",\"width\":510,\"height\":757},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"un vagabondo dei mari del sud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"10.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1656597201\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"un vagabondo dei mari del sud - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"un vagabondo dei mari del sud","og_description":"Author: bernard moitessierPublisher: Ugo Mursia EditoreISBN: LDM1656597201","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:31:26+00:00","og_image":[{"width":510,"height":757,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-mursia-quelli-di-capo-horn-2000-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;10,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/","name":"un vagabondo dei mari del sud - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-mursia-quelli-di-capo-horn-2000-3.jpg","datePublished":"2022-06-30T13:53:22+00:00","dateModified":"2026-03-14T01:31:26+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-mursia-quelli-di-capo-horn-2000-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-mursia-quelli-di-capo-horn-2000-3.jpg","width":510,"height":757},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-ldm1656597201\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"un vagabondo dei mari del sud"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"10.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1656597201","product_condition":"new"},"df_price":10,"df_sale_price":"","df_regular_price":10,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/un-vagabondo-dei-mari-del-sud-bernard-moitessier-mursia-quelli-di-capo-horn-2000-3-202x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/60969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=60969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/122139"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=60969"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=60969"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=60969"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=60969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}