{"id":60961,"date":"2022-06-30T15:26:08","date_gmt":"2022-06-30T13:26:08","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/ultimo-paradiso-folco-quilici-ldm1656595566\/"},"modified":"2026-03-14T02:31:31","modified_gmt":"2026-03-14T01:31:31","slug":"ultimo-paradiso-folco-quilici-ldm1656595566","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/ultimo-paradiso-folco-quilici-ldm1656595566\/","title":{"rendered":"ultimo paradiso"},"content":{"rendered":"<p><strong>Raro esemplare della seconda edizione di Leonardo Da Vinci Editrice del 1960 in buono stato di conservazione, collana &#8220;Piccolo Orizzonte&#8221;. In-16, legatura editoriale telata avorio con incisioninere al piatto anteriore e al dorso; sovraccoperta in carta (strappata in prima nei pressi del dorso e sciupata in prima e quarta ai tagli) illustrata a colori con alette; 104 pp., con risguardi illustrati in arancione, alcune illustrazioni in nero nel testo e numerose tavole fotografiche in nero fuori testo.<\/strong><\/p>\n<p>Dalle pagine del libro: <em>[&#8230;] Me ne sarei reso conto pi&ugrave; tardi, molto tempo dopo, quando, dopo mesi e mesi di Pacifico, avrei cominciato a tirar le somme sulle impressioni generali del viaggio. Mi sarei reso conto allora, nel ricordo, che le isole visitate mi restavano in mente con un aggettivo accanto, il pi&ugrave; semplice ed il pi&ugrave; banale fra tutti gli aggettivi che potessi pensare per esprimere un concetto.<\/em><\/p>\n<p><em>E questo perch&eacute; la sensazione che mi avrebbero dato le Isole ad ogni approdo, sarebbe stata sempre una sensazione elementare sulla quale non avrei mai dovuto restare a pensare molto per analizzarne la sostanza. Se posso paragonare le citt&agrave; o le regioni delle nostre terre occidentali &#8211; dico per dire, la Bretagna, Venezia, Madrid, il Tirolo o Edimburgo, eccetera, eccetera &#8211; a delle donne intellettuali un po&#8217; zitelle e quindi piene di complessi mentali e sessuali, paragonerei le Isole del Pacifico &#8211; Samoa, le Figi, e Tahiti, e Bora-Bora, e tutte le altre &#8211; alle simpatiche ragazze di un balletto che hanno poche ma chiare idee, sanno d&#8217;esser belle ed oltre a questo si occupano al massimo d&#8217;essere una bionda, l&#8217;altra bruna, una alta, un&#8217;altra magra, e questo &egrave; tutto.<\/em><\/p>\n<p><em>Cos&igrave; sono le Isole dei Mari del Sud. [&#8230;]<\/em><\/p>\n<p><em>Non erano stati i cieli, le lagune, i picchi rocciosi emergenti dal verde delle foreste di cocco, non era stata la musica o il profumo che stagnavano nell&#8217;aria, n&eacute; alcun altro elemento &#8211; sia pur bello, incantato e unico che le Isole possono offrire &#8211; a far chiamare quelle terre del Pacifico&nbsp;<\/em>Ultimo Paradiso<em>, ma qualcosa di pi&ugrave; prezioso, di pi&ugrave; nascosto.<\/em><\/p>\n<p><em>L&#8217;ultimo paradiso lo si scopre nei Mari del Sud vivendo insieme ed amando la gente delle Isole. Penetrando la loro felicit&agrave;, sempre nuova per un continuo contatto con la Natura, e sentendo che essa &egrave; difesa e protetta dalla forza di un mare sconfinato, si comprende perch&eacute; quegli uomini e quelle donne sono sempre sereni, pieni di gioia, gioia d&#8217;amare, gioia di vivere, di lottare, di non far nulla, pieni di gioia di vivere. [&#8230;]<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>folco quilici<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>leonardo da vinci editrice<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1656595566<\/p>\n","protected":false},"featured_media":122087,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805,2607],"product_tag":[],"class_list":{"0":"post-60961","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","7":"product_cat-narrative","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ultimo paradiso - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ultimo paradiso\" \/>\n<meta property=\"og:description\" content=\"Author: folco quiliciPublisher: leonardo da vinci editriceISBN: LDM1656595566\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/ultimo-paradiso-folco-quilici-ldm1656595566\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:31:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/ultimo-paradiso-folco-quilici-leonardo-da-vinci-editrice-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"518\" \/>\n\t<meta property=\"og:image:height\" content=\"709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/ultimo-paradiso-folco-quilici-ldm1656595566\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/ultimo-paradiso-folco-quilici-ldm1656595566\\\/\",\"name\":\"ultimo paradiso - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/ultimo-paradiso-folco-quilici-ldm1656595566\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/ultimo-paradiso-folco-quilici-ldm1656595566\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/ultimo-paradiso-folco-quilici-leonardo-da-vinci-editrice-3.jpg\",\"datePublished\":\"2022-06-30T13:26:08+00:00\",\"dateModified\":\"2026-03-14T01:31:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/ultimo-paradiso-folco-quilici-ldm1656595566\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/ultimo-paradiso-folco-quilici-ldm1656595566\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/ultimo-paradiso-folco-quilici-ldm1656595566\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/ultimo-paradiso-folco-quilici-leonardo-da-vinci-editrice-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/ultimo-paradiso-folco-quilici-leonardo-da-vinci-editrice-3.jpg\",\"width\":518,\"height\":709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/ultimo-paradiso-folco-quilici-ldm1656595566\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ultimo paradiso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"15.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1656595566\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ultimo paradiso - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"ultimo paradiso","og_description":"Author: folco quiliciPublisher: leonardo da vinci editriceISBN: LDM1656595566","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/ultimo-paradiso-folco-quilici-ldm1656595566\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:31:31+00:00","og_image":[{"width":518,"height":709,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/ultimo-paradiso-folco-quilici-leonardo-da-vinci-editrice-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;15,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/ultimo-paradiso-folco-quilici-ldm1656595566\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/ultimo-paradiso-folco-quilici-ldm1656595566\/","name":"ultimo paradiso - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/ultimo-paradiso-folco-quilici-ldm1656595566\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/ultimo-paradiso-folco-quilici-ldm1656595566\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/ultimo-paradiso-folco-quilici-leonardo-da-vinci-editrice-3.jpg","datePublished":"2022-06-30T13:26:08+00:00","dateModified":"2026-03-14T01:31:31+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/ultimo-paradiso-folco-quilici-ldm1656595566\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/ultimo-paradiso-folco-quilici-ldm1656595566\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/ultimo-paradiso-folco-quilici-ldm1656595566\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/ultimo-paradiso-folco-quilici-leonardo-da-vinci-editrice-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/ultimo-paradiso-folco-quilici-leonardo-da-vinci-editrice-3.jpg","width":518,"height":709},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/ultimo-paradiso-folco-quilici-ldm1656595566\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"ultimo paradiso"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"15.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1656595566","product_condition":"new"},"df_price":15,"df_sale_price":"","df_regular_price":15,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/ultimo-paradiso-folco-quilici-leonardo-da-vinci-editrice-3-219x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/60961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=60961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/122087"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=60961"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=60961"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=60961"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=60961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}