{"id":60690,"date":"2022-06-24T14:48:23","date_gmt":"2022-06-24T12:48:23","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/"},"modified":"2026-03-14T02:33:03","modified_gmt":"2026-03-14T01:33:03","slug":"il-grande-libro-del-mare-aa-vv-ldm1656074902","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/","title":{"rendered":"il grande libro del mare"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione di Nautica Editrice del 1972 in ottimo stato di conservazione. In-4, legatura editoriale con copertina rigida cartonata blu in similpelle con incisioni bianche al piatto anteriore e al dorso; sovraccoperta in carta (leggermente usurata ai bordi e con segni di scoloritura in quarta e sulle alette) illustrata a colori con alette; 200 pp. + 10 pp. non numerate, con oltre 220 illustrazioni in nero e a colori nel testo.<\/strong><\/p>\n<p><strong>Traduzioni a cura di Gianfranco Benati, Gina Barnab&egrave; Bosisio, Riccardo M. degli Uberti, Filippo Massara.<\/strong><\/p>\n<p>Dall&#8217;aletta anteriore:&nbsp;<em>La conquista del mare &egrave;&nbsp;<\/em>un&#8217;avventura affascinante come la conquista dello spazio<em> cos&igrave; ha scritto il Comandante Cousteau. E&#8217; questa per&ograve; una conquista alla portata di tutti e che ci impegna alla conoscenza di questo elemento che &egrave; stato all&#8217;origine della nostra vita e che sar&agrave; domani fondamento per la nostra sopravvivenza.<\/em><\/p>\n<p>Il Grande Libro del Mare&nbsp;<em>&egrave; un invito e una guida a conoscere questo mondo meraviglioso non solo nei suoi aspetti fisici e biologici ma anche per il grande significato che il mare ha avuto nella storia delle civilt&agrave;.<\/em><\/p>\n<p><em>Nelle sue pagine riviviamo le grandi scoperte, dai fenici che superarono le Colonne d&#8217;Ercole ai vichinghi a cui si deve la scoperta dell&#8217;Islanda e delle coste del Labrador fino a Cristoforo Colombo, Vasco de Gama e Magellano che per primo comp&igrave; il giro del mondo.<\/em><\/p>\n<p><em>Dalle ricchezze del mare l&#8217;uomo trover&agrave; in futuro i mezzi della sua sussistenza. Dal mare come da un&#8217;immensa fattoria sottomarino l&#8217;uomo potr&agrave; trarre i suoi alimenti, dal mare ricaver&agrave; energia attraverso lo sfruttamento dei giacimenti petroliferi che giacciono nelle sue profondit&agrave;; ma sopratutto, attraverso i procedimenti di desalinizzazione trarr&agrave; l&#8217;acqua, il pi&ugrave; prezioso e indispensabile degli elementi.<\/em><\/p>\n<p><em>Il mare &egrave; forse il bene pi&ugrave; grande che ha oggi l&#8217;umanit&agrave;, un bene inestimabile che dobbiamo conoscere per difenderlo dagli inquinamenti che lo minacciano mettendo in pericolo la sopravvivenza stessa dell&#8217;uomo.<\/em><\/p>\n<p>Il Grande Libro del Mare<em> con i testi di alcuni tra i pi&ugrave; famosi esperti europei, con oltre 120 illustrazioni e 100 disegni costituisce una completa antologia per la conoscenza di questo mondo meraviglioso.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>aa.vv.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>nautica editrice<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1656074902<\/p>\n","protected":false},"featured_media":156479,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2606,2741],"product_tag":[],"class_list":{"0":"post-60690","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-encyclopedias-atlases-and-handbooks","7":"product_cat-navigation-history","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>il grande libro del mare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"il grande libro del mare\" \/>\n<meta property=\"og:description\" content=\"Author: aa.vv.Publisher: nautica editriceISBN: LDM1656074902\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:33:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-grande-libro-del-mare-nautica-editrice.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"619\" \/>\n\t<meta property=\"og:image:height\" content=\"711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;39,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-grande-libro-del-mare-aa-vv-ldm1656074902\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-grande-libro-del-mare-aa-vv-ldm1656074902\\\/\",\"name\":\"il grande libro del mare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-grande-libro-del-mare-aa-vv-ldm1656074902\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-grande-libro-del-mare-aa-vv-ldm1656074902\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-grande-libro-del-mare-nautica-editrice.jpg\",\"datePublished\":\"2022-06-24T12:48:23+00:00\",\"dateModified\":\"2026-03-14T01:33:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-grande-libro-del-mare-aa-vv-ldm1656074902\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-grande-libro-del-mare-aa-vv-ldm1656074902\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-grande-libro-del-mare-aa-vv-ldm1656074902\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-grande-libro-del-mare-nautica-editrice.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-grande-libro-del-mare-nautica-editrice.jpg\",\"width\":619,\"height\":711},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-grande-libro-del-mare-aa-vv-ldm1656074902\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"il grande libro del mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"39.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1656074902\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"il grande libro del mare - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"il grande libro del mare","og_description":"Author: aa.vv.Publisher: nautica editriceISBN: LDM1656074902","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:33:03+00:00","og_image":[{"width":619,"height":711,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-grande-libro-del-mare-nautica-editrice.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;39,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/","name":"il grande libro del mare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-grande-libro-del-mare-nautica-editrice.jpg","datePublished":"2022-06-24T12:48:23+00:00","dateModified":"2026-03-14T01:33:03+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-grande-libro-del-mare-nautica-editrice.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-grande-libro-del-mare-nautica-editrice.jpg","width":619,"height":711},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-grande-libro-del-mare-aa-vv-ldm1656074902\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"il grande libro del mare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"39.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1656074902","product_condition":"new"},"df_price":39,"df_sale_price":"","df_regular_price":39,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-grande-libro-del-mare-nautica-editrice-261x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/60690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=60690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/156479"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=60690"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=60690"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=60690"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=60690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}