{"id":60582,"date":"2022-06-23T13:01:43","date_gmt":"2022-06-23T11:01:43","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/"},"modified":"2026-03-14T02:33:50","modified_gmt":"2026-03-14T01:33:50","slug":"il-mio-atlantico-ambrogio-fogar-ldm1655982102","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/","title":{"rendered":"il mio atlantico"},"content":{"rendered":"<p><strong>Raro esemplare della prima dizione di Bietti del 1973 in perfetto stato di conservazione, collana &ldquo;Caleidoscopio&rdquo;. In-8, legatura editoriale telata grigia con incisioni bianche al dorso; sovraccoperta in carta illustrata a colori con alette; 196 pp., con due illustrazioni in nero nel testo e numerose fotografie in nero e a colori fuori testo.<\/strong><\/p>\n<p>Dall&#8217;aletta anteriore:&nbsp;<em>Il grande protagonista di quest&#8217;opera &egrave; il mare, l&#8217;oceanica distesa dell&#8217;Atlantico, con tutte le implicazioni e i significati che assume di volta in volta per l&#8217;uomo che lo deve affrontare.<\/em><\/p>\n<p><em>Il navigare sull&#8217;Atlantico in barca a vela significa un contatto effettivo e immediato, senza tramiti di sorta, tra l&#8217;uomo e il mare, tra l&#8217;uomo e la natura. Significa libert&agrave;: libert&agrave; di spaziare all&#8217;infinito, libert&agrave; da vincoli d&#8217;ordine umano e sociale; libert&agrave; anche nell&#8217;autodisciplina e nella fatica, perch&eacute; ogni regola viene liberamente scelta e seguita. Significa vivere una dimensione umana pi&ugrave; semplice, pi&ugrave; vera, pi&ugrave; sostanziale. Significa il piacere d&#8217;immedesimarsi nella natura e, se necessario, di cimentarsi direttamente con essa, senza schermi e diaframmi. Significa infine ritrovare quel giusto senso delle proporzioni e dei valori umani che l&#8217;odierna societ&agrave; tecnologica e consumistica tende a svilire e dissacrare.<\/em><\/p>\n<p><em>Questo rapporto uomo-mare nel racconto di Fogar &egrave; sempre posto in primo piano, anche se nelle varie parti del libro assume aspetti e proporzioni diversi. Il diario della traversata&nbsp;<\/em>in solitario<em>, con i suoi problemi di adattamento a un ambiente spesso difficile o addirittura ostile e senza l&#8217;aiuto pratico e psicologico di nessun altro essere umano, delinea infatti una realt&agrave; ben diversa da quella che si evidenzia dal resoconto della&nbsp;<\/em>Cape-Town &#8211; Rio de Janeiro<em>, in cui i problemi nascevano invece dalla presenza di un equipaggio di cinque persone necessariamente obbligate a convivere nel ristretto spazio di una barca a vela. E ancora diversa &egrave; la dimensione in cui si svolge la narrazione della&nbsp;<\/em>Regata di Malta<em>, gara molto breve e&nbsp;<\/em>tirata<em>: una dimensione competitiva e agonistica che nelle altre imprese non era avvertibile e che non mancher&agrave; d&#8217;interessare e entusiasmare il lettore.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>1972 transatlantica in solitario plymouth &#8211; newport \/ 1973 seconda regata atlantica cape town &#8211; rio de janeiro<\/p>\n<p class=\"autore\"><span>Author: <\/span>ambrogio fogar<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni bietti<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1655982102<\/p>\n","protected":false},"featured_media":120430,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,2805,2607],"product_tag":[],"class_list":{"0":"post-60582","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-logbooks-and-travel-reports","8":"product_cat-narrative","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>il mio atlantico - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"il mio atlantico\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 1972 transatlantica in solitario plymouth - newport \/ 1973 seconda regata atlantica cape town - rio de janeiroAuthor: ambrogio fogarPublisher: edizioni biettiISBN: LDM1655982102\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T01:33:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-mio-atlantico-ambrogio-fogar-bietti-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"501\" \/>\n\t<meta property=\"og:image:height\" content=\"711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;29,20\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\\\/\",\"name\":\"il mio atlantico - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-mio-atlantico-ambrogio-fogar-bietti-6.jpg\",\"datePublished\":\"2022-06-23T11:01:43+00:00\",\"dateModified\":\"2026-03-14T01:33:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-mio-atlantico-ambrogio-fogar-bietti-6.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-mio-atlantico-ambrogio-fogar-bietti-6.jpg\",\"width\":501,\"height\":711},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"il mio atlantico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"29.20\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1655982102\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"il mio atlantico - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"il mio atlantico","og_description":"Subtitle: 1972 transatlantica in solitario plymouth - newport \/ 1973 seconda regata atlantica cape town - rio de janeiroAuthor: ambrogio fogarPublisher: edizioni biettiISBN: LDM1655982102","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T01:33:50+00:00","og_image":[{"width":501,"height":711,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-mio-atlantico-ambrogio-fogar-bietti-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;29,20","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/","name":"il mio atlantico - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-mio-atlantico-ambrogio-fogar-bietti-6.jpg","datePublished":"2022-06-23T11:01:43+00:00","dateModified":"2026-03-14T01:33:50+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-mio-atlantico-ambrogio-fogar-bietti-6.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-mio-atlantico-ambrogio-fogar-bietti-6.jpg","width":501,"height":711},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-atlantico-ambrogio-fogar-ldm1655982102\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"il mio atlantico"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"29.20","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1655982102","product_condition":"new"},"df_price":29.2,"df_sale_price":"","df_regular_price":29.2,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-mio-atlantico-ambrogio-fogar-bietti-6-211x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/60582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=60582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/120430"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=60582"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=60582"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=60582"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=60582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}