{"id":161785,"date":"2026-02-20T14:54:28","date_gmt":"2026-02-20T13:54:28","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\/"},"modified":"2026-03-14T00:01:13","modified_gmt":"2026-03-13T23:01:13","slug":"i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\/","title":{"rendered":"I portolani"},"content":{"rendered":"<p><strong>Raro esemplare dell&#8217;edizione speciale di Bramante Arte del 1992 in perfetto stato di conservazione. In-4, legatura editoriale con copertina rigida telata blu con impressioni oro al piatto anteriore e al dorso e cofanetto rigido telato blu; 320 pp., con risguardi verdi e numerosissime illustrazioni a colori e in nero nel testo. Edizione speciale realizzata in occasione del Cinquecentenario della scoperta dell&#8217;America, con la collaborazione di Marie-Madeleine Azard, Isabelle Raynaud-Nguyen e Marie-Antoinette Vannereau, la presentazione di Osvaldo Baldacci e la traduzione di Marianna Guadagnino.<\/strong><\/p>\n<p><strong>Tiratura: 1999 esemplari numerati.<\/strong><\/p>\n<p><strong>Il presente volume &egrave; racchiuso ii un cofanetto rigido cartonato avana (provvisto di custodia in carta) insieme a un secondo cofanetto rigido telato blu con impressioni oro e fettuccina rossa, che contiene una raccolta di carte nautiche dal XVI al XVII secolo realizzata dall&#8217;Istituto Poligrafico e Zecca dello Stato. La raccolta si compone di 12 tavole tirate ciascuna in 2350 esemplari con la tecnica della riproduzione litografica a 5 colori, eseguita su carta pergamena presso l&#8217;Officina Carte e Valori dell&#8217;Istituto. Il cofanetto contiene anche un ex libris da applicare al libro e il fascicolo <em>I portolani &#8211; Commenti alle tavole prescelte&nbsp;<\/em>a cura di Osvaldo Baldacci.<\/strong><\/p>\n<p>Dalla presentazione di Osvaldo Baldacci:&nbsp;<em>Questa opera &egrave; frutto della collaborazione di noti e benemeriti studiosi di geocartografia, che hanno ripreso un argomento che nei nostri tempi &egrave; alquanto desueto. Si tratta infatti della geocartografia a rombi di vento, necessario strumento della navigazione a vela nella continuit&agrave; dell&#8217;arco dei secoli dal XIII al XVII incluso.<\/em><\/p>\n<p><em>Il testo inizia con una INTRODUZIONE (pp. 3-28) di MICHEL MOLLAT DU JOURDIN, membro de l&#8217;Institut e dell&#8217;Acad&eacute;mie de Marine, professore emerito della Universit&agrave; la Sorbonne.<\/em><\/p>\n<p><em>Questa introduzione presenta una concettosa linea di ricerca, chiaramente espositiva e molto utile per chi voglia comprendere la geocarta a rombi di vento nella pluralit&agrave; dei suoi significati. [&#8230;]<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>Carte nautiche dal XIII al XVII secolo<\/p>\n<p class=\"autore\"><span>Author: <\/span>Monique de La Ronci\u00e8re &#8211; Michel Mollat du Jourdin<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Bramante Arte<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1771595666<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2569,2606,2741],"product_tag":[],"class_list":{"0":"post-161785","1":"product","2":"type-product","3":"status-publish","5":"product_cat-books-navigation-history-chartography","6":"product_cat-encyclopedias-atlases-and-handbooks","7":"product_cat-navigation-history","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>I portolani - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I portolani\" \/>\n<meta property=\"og:description\" content=\"Subtitle: Carte nautiche dal XIII al XVII secoloAuthor: Monique de La Ronci\u00e8re - Michel Mollat du JourdinPublisher: Bramante ArteISBN: LDM1771595666\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:01:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"162\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;250,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\\\/\",\"name\":\"I portolani - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"datePublished\":\"2026-02-20T13:54:28+00:00\",\"dateModified\":\"2026-03-13T23:01:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"I portolani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"250.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1771595666\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"I portolani - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"I portolani","og_description":"Subtitle: Carte nautiche dal XIII al XVII secoloAuthor: Monique de La Ronci\u00e8re - Michel Mollat du JourdinPublisher: Bramante ArteISBN: LDM1771595666","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:01:13+00:00","og_image":[{"width":600,"height":162,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;250,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\/","name":"I portolani - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"datePublished":"2026-02-20T13:54:28+00:00","dateModified":"2026-03-13T23:01:13+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/i-portolani-monique-de-la-ronciere-michel-mollat-du-jourdin-ldm1771595666\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"I portolani"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"250.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"LDM1771595666","product_condition":"new"},"df_price":250,"df_sale_price":"","df_regular_price":250,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/woocommerce-placeholder-300x300.png","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/161785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=161785"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=161785"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=161785"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=161785"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=161785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}