{"id":157947,"date":"2025-11-15T13:02:56","date_gmt":"2025-11-15T12:02:56","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/the-essence-of-venezia-in-a-cup-of-tea-michele-gnesotto-9788885507043\/"},"modified":"2026-03-14T00:07:45","modified_gmt":"2026-03-13T23:07:45","slug":"the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\/","title":{"rendered":"The essence of Venice in a cup of tea (Narraplanet)"},"content":{"rendered":"<p><em>NarraT&egrave; <\/em>are <strong>pocket-sized books containing a bag of artisanal, organic tea (made in Italy)<\/strong> specially formulated for each title. The 24 pages contain the story <strong>to be read while the tea steeps<\/strong>.<\/p>\n<p><strong>Blend<\/strong>: Darjeeling Black Tea | Rooibos | Ginger | Cloves | Nutmeg<\/p>\n<p><strong>Infusion time<\/strong>: 5 minutes.<\/p>\n<p><strong>Booklet<\/strong>: An unpublished story that takes approximately <strong>5 minutes to read<\/strong>, equivalent to the time needed for the infusion. Written by <strong>Michele Gnesotto<\/strong> to simply capture and convey the heart, character and <strong>soul of Venice&nbsp;<\/strong>and its people. A true <em>Souvenir Tea<\/em> printed on <strong>recycled paper<\/strong>, lovingly hand-assembled in Italy. The booklet also contains a section of <strong>short information<\/strong> useful for learning about the unique features that make Venice famous worldwide, along with a <strong>chronology of unmissable events<\/strong>. The <em>Unusual Top Ten <\/em>features <strong>10 lesser-known places<\/strong> &mdash; near the most important monuments &mdash; but equally beautiful. Finally, there are suggestions for <strong>what to eat, drink and shop<\/strong>. The QR code on the last page provides access to <strong>multimedia content <\/strong>with over an hour of additional entertainment.<\/p>\n<p>Languages: English and Italian<\/p>\n<p>Edition: 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>Michele Gnesotto<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Narrat\u00e8 (Narrafood Edizioni)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788885507043<\/p>\n","protected":false},"featured_media":162862,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2811],"product_tag":[],"class_list":{"0":"post-157947","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-short-stories","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The essence of Venice in a cup of tea (Narraplanet) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The essence of Venice in a cup of tea (Narraplanet)\" \/>\n<meta property=\"og:description\" content=\"Author: Michele GnesottoPublisher: Narrat\u00e8 (Narrafood Edizioni)ISBN: 9788885507043\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:07:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-essenza-di-venezia-in-un-te-michele-gnesotto-narrate-narrafood-edizioni-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"567\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;6,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\\\/\",\"name\":\"The essence of Venice in a cup of tea (Narraplanet) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/l-essenza-di-venezia-in-un-te-michele-gnesotto-narrate-narrafood-edizioni-3.jpg\",\"datePublished\":\"2025-11-15T12:02:56+00:00\",\"dateModified\":\"2026-03-13T23:07:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/l-essenza-di-venezia-in-un-te-michele-gnesotto-narrate-narrafood-edizioni-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/l-essenza-di-venezia-in-un-te-michele-gnesotto-narrate-narrafood-edizioni-3.jpg\",\"width\":567,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The essence of Venice in a cup of tea (Narraplanet)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"6.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788885507043\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The essence of Venice in a cup of tea (Narraplanet) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"The essence of Venice in a cup of tea (Narraplanet)","og_description":"Author: Michele GnesottoPublisher: Narrat\u00e8 (Narrafood Edizioni)ISBN: 9788885507043","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:07:45+00:00","og_image":[{"width":567,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-essenza-di-venezia-in-un-te-michele-gnesotto-narrate-narrafood-edizioni-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;6,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\/","name":"The essence of Venice in a cup of tea (Narraplanet) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-essenza-di-venezia-in-un-te-michele-gnesotto-narrate-narrafood-edizioni-3.jpg","datePublished":"2025-11-15T12:02:56+00:00","dateModified":"2026-03-13T23:07:45+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-essenza-di-venezia-in-un-te-michele-gnesotto-narrate-narrafood-edizioni-3.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-essenza-di-venezia-in-un-te-michele-gnesotto-narrate-narrafood-edizioni-3.jpg","width":567,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/the-essence-of-venice-in-a-cup-of-tea-narraplanet-michele-gnesotto-9788885507043\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"The essence of Venice in a cup of tea (Narraplanet)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"6.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788885507043","product_condition":"new"},"df_price":6.9,"df_sale_price":"","df_regular_price":6.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-essenza-di-venezia-in-un-te-michele-gnesotto-narrate-narrafood-edizioni-3-243x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/157947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=157947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/162862"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=157947"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=157947"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=157947"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=157947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}