{"id":157631,"date":"2025-11-06T14:43:54","date_gmt":"2025-11-06T13:43:54","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/"},"modified":"2026-03-14T00:08:32","modified_gmt":"2026-03-13T23:08:32","slug":"peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/","title":{"rendered":"peter pan di j.m. barrie &#8211; tutti&#8230; a teatro!"},"content":{"rendered":"<p>Unisciti a Peter, Wendy, Trilli e Capitan Uncino in questa <strong>magnifica rivisitazione di <em>Peter Pan<\/em><\/strong>, basata sull&#8217;opera teatrale originale.<\/p>\n<p><strong>Preparati a volare verso l&#8217;Isola-che-non-c&#8217;&egrave;<\/strong>, dove i pirati solcano i sette mari e i bambini non crescono mai.<\/p>\n<p><strong>Premi la nota musicale<\/strong> su ogni pagina e lasciati trasportare in una magica avventura con <strong><em>Chopin<\/em>, <em>Wagner<\/em>, <em>Debussy <\/em>e molti altri<\/strong>.<\/p>\n<p>Sei seduto comodamente? Allora, che lo spettacolo abbia inizio!<\/p>\n<p>Et&agrave;: <strong>3+<\/strong><\/p>\n<p>Edizione: 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>katie cotton &#8211; illustrazioni di ella beech<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>IdeeAli (Il Castello)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788836122561<\/p>\n","protected":false},"featured_media":157629,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2614,2617],"product_tag":[],"class_list":{"0":"post-157631","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-illustrated-books-and-fiction","7":"product_cat-illustrated-books-and-fiction-6-9-years","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>peter pan di j.m. barrie - tutti... a teatro! - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"peter pan di j.m. barrie - tutti... a teatro!\" \/>\n<meta property=\"og:description\" content=\"Author: katie cotton - illustrazioni di ella beechPublisher: IdeeAli (Il Castello)ISBN: 9788836122561\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:08:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/peter-pan-di-j-m-barie-tutti-a-teatro-cotton-beech.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"582\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;24,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\\\/\",\"name\":\"peter pan di j.m. barrie - tutti... a teatro! - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/peter-pan-di-j-m-barie-tutti-a-teatro-cotton-beech.jpg\",\"datePublished\":\"2025-11-06T13:43:54+00:00\",\"dateModified\":\"2026-03-13T23:08:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/peter-pan-di-j-m-barie-tutti-a-teatro-cotton-beech.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/peter-pan-di-j-m-barie-tutti-a-teatro-cotton-beech.jpg\",\"width\":582,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"peter pan di j.m. barrie &#8211; tutti&#8230; a teatro!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"24.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788836122561\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"peter pan di j.m. barrie - tutti... a teatro! - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"peter pan di j.m. barrie - tutti... a teatro!","og_description":"Author: katie cotton - illustrazioni di ella beechPublisher: IdeeAli (Il Castello)ISBN: 9788836122561","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:08:32+00:00","og_image":[{"width":582,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/peter-pan-di-j-m-barie-tutti-a-teatro-cotton-beech.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;24,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/","name":"peter pan di j.m. barrie - tutti... a teatro! - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/peter-pan-di-j-m-barie-tutti-a-teatro-cotton-beech.jpg","datePublished":"2025-11-06T13:43:54+00:00","dateModified":"2026-03-13T23:08:32+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/peter-pan-di-j-m-barie-tutti-a-teatro-cotton-beech.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/peter-pan-di-j-m-barie-tutti-a-teatro-cotton-beech.jpg","width":582,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/peter-pan-di-j-m-barrie-tutti-a-teatro-katie-cotton-illustrazioni-di-ella-beech-9788836122561\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"peter pan di j.m. barrie &#8211; tutti&#8230; a teatro!"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"24.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788836122561","product_condition":"new"},"df_price":24.9,"df_sale_price":"","df_regular_price":24.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/peter-pan-di-j-m-barie-tutti-a-teatro-cotton-beech-249x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/157631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=157631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/157629"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=157631"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=157631"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=157631"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=157631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}