{"id":157088,"date":"2025-10-28T13:39:30","date_gmt":"2025-10-28T12:39:30","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/"},"modified":"2026-03-14T00:09:44","modified_gmt":"2026-03-13T23:09:44","slug":"la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/","title":{"rendered":"la grande storia della sardegna"},"content":{"rendered":"<p>La <strong>storia della <em>Sardegna<\/em><\/strong><em> <\/em>&egrave; <strong>una delle pi&ugrave; ricche e affascinanti<\/strong> del bacino mediterraneo. Vi si intrecciano <strong>civilt&agrave; autoctone, dominazioni straniere e un&rsquo;identit&agrave; forte e indomita<\/strong>.&nbsp;<em>Gianmichele Lisai<\/em> la ripercorre in questo libro con <strong>precisione storica e maestria narrativa<\/strong>, risalendo fino alle radici pi&ugrave; antiche del Paleolitico, per poi tracciare i contorni della prima vera civilt&agrave; del Mediterraneo, quella nuragica, e descrivere il traumatico impatto dei domini cartaginese e romano sul substrato locale e la successiva influenza bizantina a sua volta spezzata dalle scorrerie arabe.<\/p>\n<p>Proprio allora in <em>Sardegna <\/em>si formano i <strong>quattro giudicati autonomi<\/strong> di <em>Cagliari<\/em>, <em>Torres<\/em>, <em>Arborea <\/em>e <em>Gallura<\/em>: un regime politico che non ha eguali nell&rsquo;Europa Medievale. Non mancano infine i capitoli sulla storia moderna e contemporanea: il periodo aragonese e poi spagnolo, che trasform&ograve; profondamente l&rsquo;isola anche dal punto di vista linguistico, la nascita del Regno di Sardegna e l&rsquo;avvento dei Savoia, i moti antipiemontesi e la non facile unificazione italiana, fino ai nostri giorni.<\/p>\n<p>La vita nei millenni della &laquo;perla dell&rsquo;occidente mediterraneo&raquo;: <strong>oltre i clich&eacute; turistici<\/strong>, tutto quello che c&rsquo;&egrave; da sapere sulla storia di un&rsquo;isola unica e meravigliosa.<\/p>\n<p>Tra gli argomenti trattati:<\/p>\n<ul>\n<li>I primi uomini in <em>Sardegna<\/em><\/li>\n<li>I monumenti del nuragico classico<\/li>\n<li>L&rsquo;egemonia punica tra il VI e il III secolo a.C.<\/li>\n<li>Il caso <em>Scauro <\/em>tra clientele e corruzione sul finire dell&rsquo;et&agrave; repubblicana<\/li>\n<li>Il periodo bizantino tra le lettere di <em>Gregorio Magno<\/em><\/li>\n<li>La nascita dei giudicati sardi<\/li>\n<li>L&rsquo;occupazione aragonese di <em>Cagliari<\/em><\/li>\n<li>I primi tempi degli <em>Asburgo<\/em>, tra nuovi equilibri e scorrerie<\/li>\n<li>Il partito sardo d&rsquo;azione come esito della Grande Guerra<\/li>\n<li>L&rsquo;isola negli anni dell&rsquo;Anonima Sequestri Sarda<\/li>\n<\/ul>\n<p>Edizione: 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>dalle culture prenuragiche ai quattro giudicati, dagli aragonesi ai savoia, un racconto storico completo, ricco di curiosit\u00e0, luoghi e personaggi eccezionali.<\/p>\n<p class=\"autore\"><span>Author: <\/span>gianmichele lisai<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>newton compton editori<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788822797971<\/p>\n","protected":false},"featured_media":157086,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2575],"product_tag":[],"class_list":{"0":"post-157088","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-navigation-history-other-studies","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>la grande storia della sardegna - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"la grande storia della sardegna\" \/>\n<meta property=\"og:description\" content=\"Subtitle: dalle culture prenuragiche ai quattro giudicati, dagli aragonesi ai savoia, un racconto storico completo, ricco di curiosit\u00e0, luoghi e personaggi eccezionali.Author: gianmichele lisaiPublisher: newton compton editoriISBN: 9788822797971\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:09:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/grande-storia-della-sardegna-lisai.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"778\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\\\/\",\"name\":\"la grande storia della sardegna - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/grande-storia-della-sardegna-lisai.jpg\",\"datePublished\":\"2025-10-28T12:39:30+00:00\",\"dateModified\":\"2026-03-13T23:09:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/grande-storia-della-sardegna-lisai.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/grande-storia-della-sardegna-lisai.jpg\",\"width\":500,\"height\":778},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"la grande storia della sardegna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788822797971\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"la grande storia della sardegna - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"la grande storia della sardegna","og_description":"Subtitle: dalle culture prenuragiche ai quattro giudicati, dagli aragonesi ai savoia, un racconto storico completo, ricco di curiosit\u00e0, luoghi e personaggi eccezionali.Author: gianmichele lisaiPublisher: newton compton editoriISBN: 9788822797971","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:09:44+00:00","og_image":[{"width":500,"height":778,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/grande-storia-della-sardegna-lisai.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/","name":"la grande storia della sardegna - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/grande-storia-della-sardegna-lisai.jpg","datePublished":"2025-10-28T12:39:30+00:00","dateModified":"2026-03-13T23:09:44+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/grande-storia-della-sardegna-lisai.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/grande-storia-della-sardegna-lisai.jpg","width":500,"height":778},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-grande-storia-della-sardegna-gianmichele-lisai-9788822797971\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"la grande storia della sardegna"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788822797971","product_condition":"new"},"df_price":14.9,"df_sale_price":"","df_regular_price":14.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/grande-storia-della-sardegna-lisai-193x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/157088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=157088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/157086"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=157088"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=157088"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=157088"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=157088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}