{"id":156703,"date":"2025-10-17T18:17:09","date_gmt":"2025-10-17T16:17:09","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/venezia-esoterica-luca-colferai-9788822794987\/"},"modified":"2026-03-14T00:10:40","modified_gmt":"2026-03-13T23:10:40","slug":"venezia-esoterica-luca-colferai-9788822794987","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venezia-esoterica-luca-colferai-9788822794987\/","title":{"rendered":"venezia esoterica"},"content":{"rendered":"<p>Un viaggio attraverso <strong>la storia e i luoghi di Venezia<\/strong>, alla ricerca delle tracce nascoste tra calli e canali di <strong>alchimia, occultismo, magia, astrologia, credenze popolari, ciarlataneria, negromanzia, cabala e arti divinatorie<\/strong>. Simboli arcani, segni dimenticati e fraintesi, che raccontano <strong>antichi misteri<\/strong> e personaggi dal fascino immortale. Dalle oscure allegorie medievali scolpite a San Marco alla figura controversa e ammaliante di Casanova, dagli alchimisti all&rsquo;editoria magica rinascimentale, dalla stregoneria agli indovini e medici esoterici di epoca barocca, Luca Colferai ricostruisce un affascinante mosaico di <strong>storie misteriose<\/strong>, capace di restituire nuovi significati a <strong>luoghi leggendari <\/strong>o anche ad angoli pi&ugrave; nascosti, e di indagare l&rsquo;immaginario collettivo delle varie epoche di una citt&agrave; unica come Venezia.<\/p>\n<p>Tra gli argomenti trattati:<\/p>\n<ul>\n<li><strong>Il lungo viaggio del leone<\/strong><\/li>\n<li><strong>Piazza San Marco<\/strong>: simboli e arcani tra le decorazioni della basilica<\/li>\n<li><strong>Animali e creature fantastiche<\/strong> dal Medioevo<\/li>\n<li><strong>Streghe e indovini, tarocchi e segreti<\/strong><\/li>\n<li>L&rsquo;emblema della <strong>fortuna<\/strong><\/li>\n<li>I bassorilievi alchemici di <strong>Longhena<\/strong><\/li>\n<li><strong>Massoni e avventurieri esoterici<\/strong><\/li>\n<li><strong>Giacomo Casanova<\/strong>, esoterico, cabalista, mago per necessit&agrave;<\/li>\n<li><strong>Cagliostro<\/strong>, il grande ciarlatano<\/li>\n<li>Le chiese massoniche di <strong>Santa Maria Maddalena e San Simeone Grande<\/strong><\/li>\n<\/ul>\n<p>Edizione: 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>tra canali e misteri: alchimia, magia, simboli nascosti e figure leggendarie rivelano il volto occulto di venezia<\/p>\n<p class=\"autore\"><span>Author: <\/span>luca colferai<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>newton compton editori<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788822794987<\/p>\n","protected":false},"featured_media":156701,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3065,2985],"product_tag":[],"class_list":{"0":"post-156703","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-maritime-republics","7":"product_cat-mythology","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>venezia esoterica - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"venezia esoterica\" \/>\n<meta property=\"og:description\" content=\"Subtitle: tra canali e misteri: alchimia, magia, simboli nascosti e figure leggendarie rivelano il volto occulto di veneziaAuthor: luca colferaiPublisher: newton compton editoriISBN: 9788822794987\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venezia-esoterica-luca-colferai-9788822794987\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:10:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venezia-esoterica-tra-canali-e-misteri-alchimia-magia-simboli-nascosti-e-figure-leggendarie-rivelano-occulto-luca-colferai-newton-compton.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"778\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venezia-esoterica-luca-colferai-9788822794987\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venezia-esoterica-luca-colferai-9788822794987\\\/\",\"name\":\"venezia esoterica - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venezia-esoterica-luca-colferai-9788822794987\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venezia-esoterica-luca-colferai-9788822794987\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/venezia-esoterica-tra-canali-e-misteri-alchimia-magia-simboli-nascosti-e-figure-leggendarie-rivelano-occulto-luca-colferai-newton-compton.jpg\",\"datePublished\":\"2025-10-17T16:17:09+00:00\",\"dateModified\":\"2026-03-13T23:10:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venezia-esoterica-luca-colferai-9788822794987\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venezia-esoterica-luca-colferai-9788822794987\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venezia-esoterica-luca-colferai-9788822794987\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/venezia-esoterica-tra-canali-e-misteri-alchimia-magia-simboli-nascosti-e-figure-leggendarie-rivelano-occulto-luca-colferai-newton-compton.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/venezia-esoterica-tra-canali-e-misteri-alchimia-magia-simboli-nascosti-e-figure-leggendarie-rivelano-occulto-luca-colferai-newton-compton.jpg\",\"width\":500,\"height\":778},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/venezia-esoterica-luca-colferai-9788822794987\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"venezia esoterica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788822794987\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"venezia esoterica - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"venezia esoterica","og_description":"Subtitle: tra canali e misteri: alchimia, magia, simboli nascosti e figure leggendarie rivelano il volto occulto di veneziaAuthor: luca colferaiPublisher: newton compton editoriISBN: 9788822794987","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venezia-esoterica-luca-colferai-9788822794987\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:10:40+00:00","og_image":[{"width":500,"height":778,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venezia-esoterica-tra-canali-e-misteri-alchimia-magia-simboli-nascosti-e-figure-leggendarie-rivelano-occulto-luca-colferai-newton-compton.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venezia-esoterica-luca-colferai-9788822794987\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venezia-esoterica-luca-colferai-9788822794987\/","name":"venezia esoterica - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venezia-esoterica-luca-colferai-9788822794987\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venezia-esoterica-luca-colferai-9788822794987\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venezia-esoterica-tra-canali-e-misteri-alchimia-magia-simboli-nascosti-e-figure-leggendarie-rivelano-occulto-luca-colferai-newton-compton.jpg","datePublished":"2025-10-17T16:17:09+00:00","dateModified":"2026-03-13T23:10:40+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venezia-esoterica-luca-colferai-9788822794987\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venezia-esoterica-luca-colferai-9788822794987\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venezia-esoterica-luca-colferai-9788822794987\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venezia-esoterica-tra-canali-e-misteri-alchimia-magia-simboli-nascosti-e-figure-leggendarie-rivelano-occulto-luca-colferai-newton-compton.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venezia-esoterica-tra-canali-e-misteri-alchimia-magia-simboli-nascosti-e-figure-leggendarie-rivelano-occulto-luca-colferai-newton-compton.jpg","width":500,"height":778},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/venezia-esoterica-luca-colferai-9788822794987\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"venezia esoterica"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788822794987","product_condition":"new"},"df_price":14.9,"df_sale_price":"","df_regular_price":14.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/venezia-esoterica-tra-canali-e-misteri-alchimia-magia-simboli-nascosti-e-figure-leggendarie-rivelano-occulto-luca-colferai-newton-compton-193x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/156703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=156703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/156701"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=156703"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=156703"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=156703"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=156703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}