{"id":154825,"date":"2025-09-17T11:12:09","date_gmt":"2025-09-17T09:12:09","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/"},"modified":"2026-03-14T00:13:35","modified_gmt":"2026-03-13T23:13:35","slug":"la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/","title":{"rendered":"la radio vhf di bordo"},"content":{"rendered":"<p>Non il classico libro sul VHF, ma <strong>una guida che unisce teoria, casi reali e strumenti pratici<\/strong> per avere sempre una radio efficiente a bordo.<\/p>\n<p>Non &egrave; una semplice guida teorica, ma un <strong>manuale tecnico-operativo<\/strong> pensato per chi vive davvero il mare. E&#8217; stato scritto per <strong>armatori, tecnici, diportisti e professionisti<\/strong> che desiderano risolvere problemi direttamente a bordo e avere un impianto radio sempre efficiente e affidabile.<\/p>\n<p><strong>Navigare in sicurezza significa poter contare su una comunicazione affidabile.<\/strong><\/p>\n<p>Con <strong>un approccio chiaro e pratico<\/strong>, arricchito da <strong>casi reali ed esempi concreti<\/strong>, il lettore imparer&agrave; a:<\/p>\n<ul>\n<li>installare correttamente la radio VHF<\/li>\n<li>individuare e risolvere i problemi pi&ugrave; comuni<\/li>\n<li>usare strumenti come SWR Meter e analizzatori d&#8217;antenna<\/li>\n<li>applicare tecniche di manutenzione stagionale per garantire efficienza e durata<\/li>\n<li>migliorare la qualit&agrave; e la portata della trasmissione<\/li>\n<li>utilizzare al meglio il DSC e le chiamate d&#8217;emergenza<\/li>\n<li>orientarsi tra normative, licenze e obblighi legali<\/li>\n<\/ul>\n<p>Il volume, inoltre, &egrave; completato da:<\/p>\n<ul>\n<li>checklist operative<\/li>\n<li>schede diagnostiche<\/li>\n<li>glossario tecnico<\/li>\n<li>strumenti consigliati e aneddoti vissuti dall&#8217;autore (che donano autenticit&agrave; e valore esperienziale)<\/li>\n<\/ul>\n<p>L&#8217;autore porta a bordo l&#8217;esperienza diretta di <strong>una vita dedicata al mare e alla radiocomunicazione, trasformata in una guida pratica e affidabile<\/strong>.<\/p>\n<p><strong>Una guida completa, concreta e indispensabile per chi desidera un impianto radio davvero &#8220;a prova di mare&#8221;.<\/strong><\/p>\n<p><strong>Volume autografato dall&#8217;autore.<\/strong><\/p>\n<p>Edizione: 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>installazione, manutenzione e risoluzione dei problemi<\/p>\n<p class=\"autore\"><span>Author: <\/span>guido vincenzo negri<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>guido vincenzo negri<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791221078718<\/p>\n","protected":false},"featured_media":155209,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2679],"product_tag":[],"class_list":{"0":"post-154825","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-electronics","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>la radio vhf di bordo - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"la radio vhf di bordo\" \/>\n<meta property=\"og:description\" content=\"Subtitle: installazione, manutenzione e risoluzione dei problemiAuthor: guido vincenzo negriPublisher: guido vincenzo negriISBN: 9791221078718\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:13:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/radio-vhf-di-bordo-negri-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\\\/\",\"name\":\"la radio vhf di bordo - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/radio-vhf-di-bordo-negri-9.jpg\",\"datePublished\":\"2025-09-17T09:12:09+00:00\",\"dateModified\":\"2026-03-13T23:13:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/radio-vhf-di-bordo-negri-9.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/radio-vhf-di-bordo-negri-9.jpg\",\"width\":500,\"height\":772},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"la radio vhf di bordo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"15.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791221078718\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"la radio vhf di bordo - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"la radio vhf di bordo","og_description":"Subtitle: installazione, manutenzione e risoluzione dei problemiAuthor: guido vincenzo negriPublisher: guido vincenzo negriISBN: 9791221078718","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:13:35+00:00","og_image":[{"width":500,"height":772,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/radio-vhf-di-bordo-negri-9.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;15,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/","name":"la radio vhf di bordo - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/radio-vhf-di-bordo-negri-9.jpg","datePublished":"2025-09-17T09:12:09+00:00","dateModified":"2026-03-13T23:13:35+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/radio-vhf-di-bordo-negri-9.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/radio-vhf-di-bordo-negri-9.jpg","width":500,"height":772},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-radio-vhf-di-bordo-guido-vincenzo-negri-9791221078718\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"la radio vhf di bordo"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"15.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9791221078718","product_condition":"new"},"df_price":15.9,"df_sale_price":"","df_regular_price":15.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/radio-vhf-di-bordo-negri-9-194x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/154825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=154825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/155209"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=154825"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=154825"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=154825"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=154825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}