{"id":154474,"date":"2025-09-13T12:27:49","date_gmt":"2025-09-13T10:27:49","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/"},"modified":"2026-03-14T00:13:43","modified_gmt":"2026-03-13T23:13:43","slug":"il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/","title":{"rendered":"il po dalle sorgenti al delta"},"content":{"rendered":"<p>Dalle pendici del Monviso alle ramificazioni deltizie, il fiume pi&ugrave; lungo d&rsquo;Italia scorre in un&rsquo;area popolata da circa 20 milioni di persone di cui nel tempo ha modellato i paesaggi, influenzando lo sviluppo antropico, favorendo la coltivazione di rinomati prodotti, ispirando artisti, cineasti, scrittori. Prezioso corridoio ecologico della Pianura Padana, <strong>il Po<\/strong> rivela a ogni ansa il fragile equilibrio fra uomo e natura. Questa guida ne segue i meandri attraverso quattro regioni, proponendo <strong>un viaggio terracqueo all&rsquo;insegna della sostenibilit&agrave; e della lentezza<\/strong>.<\/p>\n<p>Dal sommario:<\/p>\n<ul>\n<li>La rete dei <strong>parchi fluviali<\/strong>: storia, botanica, fauna, curiosit&agrave;, leggende e informazioni per la visita<\/li>\n<li>Nelle risaie del&nbsp;<strong>Basso Vercellese<\/strong>, tra boschi e paludi, cascine e grange, aziende agricole e canali<\/li>\n<li><strong>Tour in kayak<\/strong> da Pila all&rsquo;Isola Batteria e nelle Valli di Comacchio<\/li>\n<li><strong>Prodotti tipici, cantine e ricette<\/strong>, tanti consigli su dove assaggiare i piatti del territorio<\/li>\n<li>Dalla Sacca degli Scardovari all&rsquo;Oasi di Punta Alberete, gli spot migliori per il <strong>birdwatching nel delta<\/strong><\/li>\n<li><strong>In bicicletta sulla ciclopista <em>Destra Po<\/em><\/strong>, 124 km sull&rsquo;argine da Stellata a Gorino, con visita a uno degli ultimi esemplari di mulino fluviale<\/li>\n<li><strong>Trekking nell&rsquo;Oasi di Cannevi&egrave;<\/strong>, uno dei pochi lembi del delta sopravvissuti alle bonifiche tra il Gran Bosco della Mesola e il Po di Volano<\/li>\n<li>I set del <em>Grande Fiume<\/em> da Zavattini a Ermanno Olmi, da Lattuada a Michelangelo Antonioni: mezzo secolo di <strong>lungometraggi nella pianura<\/strong><\/li>\n<li><strong>Il ponte di barche di Boretto<\/strong> e l&rsquo;ultimo dei pontieri: l&rsquo;intenso reportage di Maurizio Silvestri<\/li>\n<li>Prendersi cura del fiume: dalle riserve MAB al progetto Po Grande, <strong>associazioni e iniziative per la sostenibilit&agrave; ambientale<\/strong><\/li>\n<\/ul>\n<p><strong>Libro con mappa staccabile.<\/strong><\/p>\n<p>Edizione: 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>in barca, in bicicletta, a piedi sulle rive del grande fiume<\/p>\n<p class=\"autore\"><span>Author: <\/span>aa.vv.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>touring club italiano (tci)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788836583751<\/p>\n","protected":false},"featured_media":154472,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2636],"product_tag":[],"class_list":{"0":"post-154474","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-lakes-and-rivers","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>il po dalle sorgenti al delta - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"il po dalle sorgenti al delta\" \/>\n<meta property=\"og:description\" content=\"Subtitle: in barca, in bicicletta, a piedi sulle rive del grande fiumeAuthor: aa.vv.Publisher: touring club italiano (tci)ISBN: 9788836583751\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:13:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-po-dalle-sorgenti-al-delta-in-barca-in-bicicletta-a-piedi-sulle-rive-del-grande-fiume-touring-club-italiano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"743\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\\\/\",\"name\":\"il po dalle sorgenti al delta - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-po-dalle-sorgenti-al-delta-in-barca-in-bicicletta-a-piedi-sulle-rive-del-grande-fiume-touring-club-italiano.jpg\",\"datePublished\":\"2025-09-13T10:27:49+00:00\",\"dateModified\":\"2026-03-13T23:13:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-po-dalle-sorgenti-al-delta-in-barca-in-bicicletta-a-piedi-sulle-rive-del-grande-fiume-touring-club-italiano.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/il-po-dalle-sorgenti-al-delta-in-barca-in-bicicletta-a-piedi-sulle-rive-del-grande-fiume-touring-club-italiano.jpg\",\"width\":500,\"height\":743},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"il po dalle sorgenti al delta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788836583751\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"il po dalle sorgenti al delta - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"il po dalle sorgenti al delta","og_description":"Subtitle: in barca, in bicicletta, a piedi sulle rive del grande fiumeAuthor: aa.vv.Publisher: touring club italiano (tci)ISBN: 9788836583751","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:13:43+00:00","og_image":[{"width":500,"height":743,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-po-dalle-sorgenti-al-delta-in-barca-in-bicicletta-a-piedi-sulle-rive-del-grande-fiume-touring-club-italiano.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/","name":"il po dalle sorgenti al delta - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-po-dalle-sorgenti-al-delta-in-barca-in-bicicletta-a-piedi-sulle-rive-del-grande-fiume-touring-club-italiano.jpg","datePublished":"2025-09-13T10:27:49+00:00","dateModified":"2026-03-13T23:13:43+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-po-dalle-sorgenti-al-delta-in-barca-in-bicicletta-a-piedi-sulle-rive-del-grande-fiume-touring-club-italiano.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-po-dalle-sorgenti-al-delta-in-barca-in-bicicletta-a-piedi-sulle-rive-del-grande-fiume-touring-club-italiano.jpg","width":500,"height":743},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-po-dalle-sorgenti-al-delta-aa-vv-9788836583751\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"il po dalle sorgenti al delta"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788836583751","product_condition":"new"},"df_price":14.9,"df_sale_price":"","df_regular_price":14.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/il-po-dalle-sorgenti-al-delta-in-barca-in-bicicletta-a-piedi-sulle-rive-del-grande-fiume-touring-club-italiano-202x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/154474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=154474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/154472"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=154474"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=154474"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=154474"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=154474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}