{"id":149262,"date":"2025-05-27T16:28:16","date_gmt":"2025-05-27T14:28:16","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/"},"modified":"2026-03-14T00:27:44","modified_gmt":"2026-03-13T23:27:44","slug":"l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/","title":{"rendered":"l&#8217;isola del tesoro"},"content":{"rendered":"<p><strong>La vita del giovane Jim Hawkins scorre tranquilla<\/strong>, alla locanda di famiglia nel villaggio sul mare non lontano da Bristol. Fino al giorno in cui, con l&rsquo;intento di nascondersi, un burbero e alcolizzato uomo di mare, che si fa chiamare capitano <strong>Billy Bones, prende in affitto una stanza proprio in quella locand<\/strong>a. Da qui in poi, la vita di Jim &egrave; <strong>un susseguirsi di incontri pericolosi, di colpi di scena, di scelte coraggiose, di rocambolesche avventure<\/strong>.<\/p>\n<p>La <strong>mappa del tesoro<\/strong> di Flint, che Billy Bones custodiva gelosamente e che tutti i peggiori filibustieri stavano cercando, finisce invece per un gioco del caso proprio nelle mani di Jim; con il dottor Livesey e con il conte Trelawney, il ragazzo si imbarca sull&rsquo;Hispaniola, alla ricerca dell&rsquo;isola e del tesoro. Convinti della facilit&agrave; dell&rsquo;impresa e della fedelt&agrave; dell&rsquo;equipaggio, i tre, affiancati da un pugno di marinai ancora fedeli, si ritroveranno invece a dover <strong>combattere contro un nutrito manipolo di pirati senza scrupoli<\/strong>, guidati da Long John Silver, imbarcatosi come cuoco di bordo. Per il giovane Jim, l&rsquo;incontro con quest&rsquo;uomo che sa essere spietato e leale, segner&agrave; non solo il suo avventuroso battesimo del mare, ma anche il suo rito di passaggio per diventare un uomo.<\/p>\n<p>Un inno alla libert&agrave; di scelta, all&rsquo;avventura pura, allo sconfinato mare, alla natura selvaggia.<\/p>\n<p>Et&agrave;: <strong>8+<\/strong><\/p>\n<p>Edizione: 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>robert louis stevenson &#8211; maurizio a.c. quarello<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>orecchio acerbo<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788832070743<\/p>\n","protected":false},"featured_media":159810,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2613,2617],"product_tag":[],"class_list":{"0":"post-149262","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-9-12-years","7":"product_cat-illustrated-books-and-fiction-6-9-years","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>l&#039;isola del tesoro - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l&#039;isola del tesoro\" \/>\n<meta property=\"og:description\" content=\"Author: robert louis stevenson - maurizio a.c. quarelloPublisher: orecchio acerboISBN: 9788832070743\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:27:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isola-del-tesoro-stevenson-quarello-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;26,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\\\/\",\"name\":\"l'isola del tesoro - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/isola-del-tesoro-stevenson-quarello-2.jpg\",\"datePublished\":\"2025-05-27T14:28:16+00:00\",\"dateModified\":\"2026-03-13T23:27:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/isola-del-tesoro-stevenson-quarello-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/isola-del-tesoro-stevenson-quarello-2.jpg\",\"width\":500,\"height\":704},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"l&#8217;isola del tesoro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"26.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788832070743\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"l'isola del tesoro - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"l'isola del tesoro","og_description":"Author: robert louis stevenson - maurizio a.c. quarelloPublisher: orecchio acerboISBN: 9788832070743","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:27:44+00:00","og_image":[{"width":500,"height":704,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isola-del-tesoro-stevenson-quarello-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;26,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/","name":"l'isola del tesoro - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isola-del-tesoro-stevenson-quarello-2.jpg","datePublished":"2025-05-27T14:28:16+00:00","dateModified":"2026-03-13T23:27:44+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isola-del-tesoro-stevenson-quarello-2.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isola-del-tesoro-stevenson-quarello-2.jpg","width":500,"height":704},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-isola-del-tesoro-robert-louis-stevenson-maurizio-a-c-quarello-9788832070743\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"l&#8217;isola del tesoro"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"26.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788832070743","product_condition":"new"},"df_price":26,"df_sale_price":"","df_regular_price":26,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/isola-del-tesoro-stevenson-quarello-2-213x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/149262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=149262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/159810"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=149262"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=149262"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=149262"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=149262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}