{"id":148190,"date":"2025-04-30T14:43:54","date_gmt":"2025-04-30T12:43:54","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/"},"modified":"2026-03-14T00:30:33","modified_gmt":"2026-03-13T23:30:33","slug":"seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/","title":{"rendered":"seashells of eastern africa"},"content":{"rendered":"<p>From the preface by Giuseppe Giulio Battaglia: <em>Our Malacological Diaries are simply a collection of photographic images produced during various trips around the world [&#8230;].<\/em><\/p>\n<p><em>The 225 species included in 54 families of marine gastropods, depicted below in 242 photographic plates, were all found by the authors, crabbed, stranded and, above all, preyed upon by octopuses, during their stays in the locations indicated in the introduction. The specimens found alive were photographed on site using a portable aquarium and then, almost always, released.<\/em><\/p>\n<p><em>For aesthetic reasons, the photographic plates only show the essential information: genus, species, dimensions, place and date of discovery. [&#8230;]<\/em><\/p>\n<p>Languages: English and Italian<\/p>\n<p>Edition: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>the malacological diaries of giuseppe giulio battaglia &amp; silvana bertoli battaglia vol. 6 \u2013 photographic research of marine molluscs in kenya &amp; tanzania<\/p>\n<p class=\"autore\"><span>Author: <\/span>giuseppe giulio battaglia &#8211; silvana bertoli battaglia<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>youcanprint<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791222711713<\/p>\n","protected":false},"featured_media":148200,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2947],"product_tag":[],"class_list":{"0":"post-148190","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-rest-of-the-world-books-malacology","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>seashells of eastern africa - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"seashells of eastern africa\" \/>\n<meta property=\"og:description\" content=\"Subtitle: the malacological diaries of giuseppe giulio battaglia &amp; silvana bertoli battaglia vol. 6 \u2013 photographic research of marine molluscs in kenya &amp; tanzaniaAuthor: giuseppe giulio battaglia - silvana bertoli battagliaPublisher: youcanprintISBN: 9791222711713\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:30:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/conchiglie-dell-africa-orientale-molluschi-marini-kenya-tanzania-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-youcanprint-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"702\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;119,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\\\/\",\"name\":\"seashells of eastern africa - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/conchiglie-dell-africa-orientale-molluschi-marini-kenya-tanzania-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-youcanprint-2.jpg\",\"datePublished\":\"2025-04-30T12:43:54+00:00\",\"dateModified\":\"2026-03-13T23:30:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/conchiglie-dell-africa-orientale-molluschi-marini-kenya-tanzania-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-youcanprint-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/conchiglie-dell-africa-orientale-molluschi-marini-kenya-tanzania-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-youcanprint-2.jpg\",\"width\":500,\"height\":702},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"seashells of eastern africa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"119.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791222711713\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"seashells of eastern africa - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"seashells of eastern africa","og_description":"Subtitle: the malacological diaries of giuseppe giulio battaglia &amp; silvana bertoli battaglia vol. 6 \u2013 photographic research of marine molluscs in kenya &amp; tanzaniaAuthor: giuseppe giulio battaglia - silvana bertoli battagliaPublisher: youcanprintISBN: 9791222711713","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:30:33+00:00","og_image":[{"width":500,"height":702,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/conchiglie-dell-africa-orientale-molluschi-marini-kenya-tanzania-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-youcanprint-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;119,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/","name":"seashells of eastern africa - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/conchiglie-dell-africa-orientale-molluschi-marini-kenya-tanzania-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-youcanprint-2.jpg","datePublished":"2025-04-30T12:43:54+00:00","dateModified":"2026-03-13T23:30:33+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/conchiglie-dell-africa-orientale-molluschi-marini-kenya-tanzania-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-youcanprint-2.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/conchiglie-dell-africa-orientale-molluschi-marini-kenya-tanzania-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-youcanprint-2.jpg","width":500,"height":702},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/seashells-of-eastern-africa-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-9791222711713\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"seashells of eastern africa"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"119.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9791222711713","product_condition":"new"},"df_price":119,"df_sale_price":"","df_regular_price":119,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/conchiglie-dell-africa-orientale-molluschi-marini-kenya-tanzania-giuseppe-giulio-battaglia-silvana-bertoli-battaglia-youcanprint-2-214x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/148190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=148190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/148200"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=148190"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=148190"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=148190"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=148190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}