{"id":146217,"date":"2025-03-22T11:43:08","date_gmt":"2025-03-22T10:43:08","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/"},"modified":"2026-03-14T00:35:50","modified_gmt":"2026-03-13T23:35:50","slug":"viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/","title":{"rendered":"viaggiatori veneziani alla scoperta della vecchia europa"},"content":{"rendered":"<p>Nel cuore dell&rsquo;<strong>et&agrave; d&rsquo;oro della Repubblica di Venezia<\/strong> vennero forgiati alcuni dei <strong>pi&ugrave; audaci viaggiatori ed esploratori d&rsquo;Europa<\/strong>. Questi veneti <strong>intrapresero viaggi straordinari nel corso dei secoli<\/strong>, sfidando le gelide acque tumultuose dei mari del nord e i pericoli delle impenetrabili foreste del sud della Germania, dando vita a una narrazione avventurosa che avrebbe affascinato le generazioni future.<\/p>\n<p><em>Viaggiatori tra miti e meraviglie d&rsquo;Europa<\/em> &egrave; un <strong>percorso affascinante attraverso le vite e le gesta di questi intrepidi avventurieri<\/strong>. Attraverso queste pagine, esploreremo i loro <strong>destini eccezionali<\/strong>, le loro <strong>scoperte straordinarie<\/strong> e le loro connessioni con le pi&ugrave; grandi figure dell&rsquo;epoca. Questi diplomatici, esploratori e viaggiatori si spinsero ben oltre i confini della loro citt&agrave; natale, aprendo nuove rotte commerciali, collezionando conoscenze scientifiche e culturali, e lasciando un&rsquo;impronta indelebile nella storia europea.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>serenissimi viaggiatori tra miti e meraviglie d&#8217;europa<\/p>\n<p class=\"autore\"><span>Author: <\/span>davide busato<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>de bastiani editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788884668707<\/p>\n","protected":false},"featured_media":146215,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3013],"product_tag":[],"class_list":{"0":"post-146217","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-everything-else-books-navigation-history-exploration","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>viaggiatori veneziani alla scoperta della vecchia europa - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"viaggiatori veneziani alla scoperta della vecchia europa\" \/>\n<meta property=\"og:description\" content=\"Subtitle: serenissimi viaggiatori tra miti e meraviglie d&#039;europaAuthor: davide busatoPublisher: de bastiani editoreISBN: 9788884668707\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:35:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-busato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;12,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\\\/\",\"name\":\"viaggiatori veneziani alla scoperta della vecchia europa - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-busato.jpg\",\"datePublished\":\"2025-03-22T10:43:08+00:00\",\"dateModified\":\"2026-03-13T23:35:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-busato.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-busato.jpg\",\"width\":500,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"viaggiatori veneziani alla scoperta della vecchia europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"12.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788884668707\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"viaggiatori veneziani alla scoperta della vecchia europa - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"viaggiatori veneziani alla scoperta della vecchia europa","og_description":"Subtitle: serenissimi viaggiatori tra miti e meraviglie d'europaAuthor: davide busatoPublisher: de bastiani editoreISBN: 9788884668707","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:35:50+00:00","og_image":[{"width":500,"height":718,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-busato.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;12,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/","name":"viaggiatori veneziani alla scoperta della vecchia europa - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-busato.jpg","datePublished":"2025-03-22T10:43:08+00:00","dateModified":"2026-03-13T23:35:50+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-busato.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-busato.jpg","width":500,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-davide-busato-9788884668707\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"viaggiatori veneziani alla scoperta della vecchia europa"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"12.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788884668707","product_condition":"new"},"df_price":12,"df_sale_price":"","df_regular_price":12,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/viaggiatori-veneziani-alla-scoperta-della-vecchia-europa-busato-209x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/146217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=146217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/146215"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=146217"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=146217"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=146217"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=146217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}