{"id":143807,"date":"2025-02-12T12:14:52","date_gmt":"2025-02-12T11:14:52","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/"},"modified":"2026-03-14T00:42:58","modified_gmt":"2026-03-13T23:42:58","slug":"filosofia-minima-del-pendolare-bjorn-larsson-9788870916928","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/","title":{"rendered":"filosofia minima del pendolare"},"content":{"rendered":"<p>Di tanto in tanto, esistono momenti in cui si pu&ograve; tirare il fiato, in cui la vita rimane come sospesa per aria, una parentesi in cui non si vuole n&eacute; questo n&eacute; quello e non si &egrave; costretti a correre: secondo <em>Bj&ouml;rn Larsson<\/em> il viaggio del pendolare &egrave; uno di questi momenti.<\/p>\n<p><em>Bj&ouml;rn Larsson<\/em> ha alle spalle <strong>un&rsquo;esistenza nomade e vagabonda a bordo di una barca, ma anche quarant&rsquo;anni di sfiancante pendolarismo<\/strong>. Pendolare incallito <strong>tra Danimarca, Svezia e Italia per lavoro e per amore<\/strong>, durante i suoi <strong>numerosi viaggi &ndash; in traghetto, treno, bus e qualche aereo<\/strong> &ndash; e migliaia di chilometri, ha osservato le abitudini e le nevrosi dei pendolari, incluso se stesso. Il risultato &egrave; <strong>un libro divertente in cui episodi di vita vissuta sono occasioni di riflessione<\/strong>, e l&rsquo;elegante lingua della letteratura si mescola al buffo chiacchiericcio quotidiano dei viaggiatori. Si passa da spunti su come scegliere i migliori posti sui mezzi di trasporto agli snervanti imprevisti che spesso tocca affrontare, passando per l&rsquo;arte di trovare il tragitto pi&ugrave; breve a considerazioni profonde sulla decadenza del linguaggio e le trasformazioni della societ&agrave;, con un occhio attento ai cambiamenti nel modo in cui viaggiamo.<\/p>\n<p>Tra <strong>citazioni dai miti letterari<\/strong> come <em>Martinson <\/em>e <em>De Beauvoir<\/em>, <em>Orwell <\/em>e <em>Beckett<\/em>, non mancano<strong> critiche al capitalismo e riflessioni sull&rsquo;isolamento durante la pandemia<\/strong>, che ha toccato profondamente chi, come lui, trova nel viaggio una ragione di vita. E <strong>c&rsquo;&egrave; spazio anche per l&rsquo;avventura, naturalmente: quando i venti del Nord soffiano sull&rsquo;&Oslash;resund e i traghetti sono in balia delle onde, &egrave; facile ricordare altre burrasche<\/strong>.<\/p>\n<p>Con leggerezza e un&rsquo;ironia che si fa aperta comicit&agrave;, <em>Larsson <\/em><strong>trasporta i suoi temi classici, come il viaggio, lo sradicamento e il bisogno di libert&agrave;, dal mondo romanzesco dei mari a quello quotidiano e urbano del trasporto pubblico<\/strong>, in <strong>un racconto che susciter&agrave; immediata simpatia in chiunque abbia vissuto, anche solo per poco, la frustrante esperienza del pendolarismo<\/strong>.&nbsp;<\/p>\n<p>Edizione: 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>bjorn larsson<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>iperborea<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788870916928<\/p>\n","protected":false},"featured_media":147315,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2981,2983,2811],"product_tag":[],"class_list":{"0":"post-143807","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-culture-and-society","7":"product_cat-literary-essays","8":"product_cat-short-stories","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>filosofia minima del pendolare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"filosofia minima del pendolare\" \/>\n<meta property=\"og:description\" content=\"Author: bjorn larssonPublisher: iperboreaISBN: 9788870916928\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:42:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/filosofia-minima-del-pendolare-larsson-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"990\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;18,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\\\/\",\"name\":\"filosofia minima del pendolare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/filosofia-minima-del-pendolare-larsson-1.jpg\",\"datePublished\":\"2025-02-12T11:14:52+00:00\",\"dateModified\":\"2026-03-13T23:42:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/filosofia-minima-del-pendolare-larsson-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/filosofia-minima-del-pendolare-larsson-1.jpg\",\"width\":500,\"height\":990},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"filosofia minima del pendolare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"18.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788870916928\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"filosofia minima del pendolare - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"filosofia minima del pendolare","og_description":"Author: bjorn larssonPublisher: iperboreaISBN: 9788870916928","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:42:58+00:00","og_image":[{"width":500,"height":990,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/filosofia-minima-del-pendolare-larsson-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;18,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/","name":"filosofia minima del pendolare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/filosofia-minima-del-pendolare-larsson-1.jpg","datePublished":"2025-02-12T11:14:52+00:00","dateModified":"2026-03-13T23:42:58+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/filosofia-minima-del-pendolare-larsson-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/filosofia-minima-del-pendolare-larsson-1.jpg","width":500,"height":990},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/filosofia-minima-del-pendolare-bjorn-larsson-9788870916928\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"filosofia minima del pendolare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"18.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788870916928","product_condition":"new"},"df_price":18,"df_sale_price":"","df_regular_price":18,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/filosofia-minima-del-pendolare-larsson-1-152x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/143807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=143807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/147315"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=143807"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=143807"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=143807"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=143807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}