{"id":140837,"date":"2024-12-07T12:11:12","date_gmt":"2024-12-07T11:11:12","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/"},"modified":"2026-03-14T00:47:54","modified_gmt":"2026-03-13T23:47:54","slug":"la-leggenda-di-ulisse-sara-prossomariti-9788822790248","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/","title":{"rendered":"la leggenda di ulisse"},"content":{"rendered":"<p><strong>Il valoroso re dall&#8217;ingegno proverbiale e il suo lungo viaggio per tornare a casa.&nbsp;L&#8217;Odissea come non l&#8217;avete mai letta.<\/strong><\/p>\n<p>Segui <strong>Ulisse<\/strong>, l&rsquo;astuto re di Itaca, mentre naviga tra <strong>mostri mitici, dee seducenti e sfide mortali<\/strong> nel suo tentativo di <strong>tornare a casa dopo la Guerra di Troia<\/strong>. Ogni pagina &egrave; un&rsquo;avventura, piena di <strong>intrighi, coraggio e stratagemmi<\/strong> per ingannare i nemici e superare tutti gli ostacoli. Dal gigantesco <strong>ciclope Polifemo <\/strong>all&rsquo;irresistibile <strong>canto delle sirene<\/strong>, dai vortici di <strong>Scilla e Cariddi <\/strong>alla magia, tanto potente quanto terribile, dell&rsquo;affascinante <strong>Circe<\/strong>: insieme al suo equipaggio, Ulisse dovr&agrave; affrontare un viaggio pieno di <strong>deviazioni e pericoli<\/strong>&nbsp;e sopportare <strong>dieci anni in balia di venti e tempeste<\/strong>, prima di poter riabbracciare la sua amata moglie Penelope. La sua &egrave; un&rsquo;avventura che ha resistito al tempo e continua a incantare lettori di tutte le et&agrave;. Questo libro ne ripercorre le tappe, conducendoci nei luoghi reali che hanno ispirato il mito e il poema omerico e svelando tutti i segreti che l&rsquo;hanno reso <strong>un capolavoro immortale della letteratura<\/strong>.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>il pi\u00f9 furbo di tutti gli eroi<\/p>\n<p class=\"autore\"><span>Author: <\/span>sara prossomariti<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>newton compton editori<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788822790248<\/p>\n","protected":false},"featured_media":140835,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2985],"product_tag":[],"class_list":{"0":"post-140837","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-mythology","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>la leggenda di ulisse - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"la leggenda di ulisse\" \/>\n<meta property=\"og:description\" content=\"Subtitle: il pi\u00f9 furbo di tutti gli eroiAuthor: sara prossomaritiPublisher: newton compton editoriISBN: 9788822790248\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:47:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/la-leggenda-di-ulisse-il-piu-furbo-di-tutti-gli-eroi-sara-prossomariti-newton-compton-editori.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;12,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\\\/\",\"name\":\"la leggenda di ulisse - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/la-leggenda-di-ulisse-il-piu-furbo-di-tutti-gli-eroi-sara-prossomariti-newton-compton-editori.jpg\",\"datePublished\":\"2024-12-07T11:11:12+00:00\",\"dateModified\":\"2026-03-13T23:47:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/la-leggenda-di-ulisse-il-piu-furbo-di-tutti-gli-eroi-sara-prossomariti-newton-compton-editori.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/la-leggenda-di-ulisse-il-piu-furbo-di-tutti-gli-eroi-sara-prossomariti-newton-compton-editori.jpg\",\"width\":500,\"height\":780},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"la leggenda di ulisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"12.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788822790248\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"la leggenda di ulisse - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"la leggenda di ulisse","og_description":"Subtitle: il pi\u00f9 furbo di tutti gli eroiAuthor: sara prossomaritiPublisher: newton compton editoriISBN: 9788822790248","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:47:54+00:00","og_image":[{"width":500,"height":780,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/la-leggenda-di-ulisse-il-piu-furbo-di-tutti-gli-eroi-sara-prossomariti-newton-compton-editori.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;12,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/","name":"la leggenda di ulisse - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/la-leggenda-di-ulisse-il-piu-furbo-di-tutti-gli-eroi-sara-prossomariti-newton-compton-editori.jpg","datePublished":"2024-12-07T11:11:12+00:00","dateModified":"2026-03-13T23:47:54+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/la-leggenda-di-ulisse-il-piu-furbo-di-tutti-gli-eroi-sara-prossomariti-newton-compton-editori.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/la-leggenda-di-ulisse-il-piu-furbo-di-tutti-gli-eroi-sara-prossomariti-newton-compton-editori.jpg","width":500,"height":780},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/la-leggenda-di-ulisse-sara-prossomariti-9788822790248\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"la leggenda di ulisse"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"12.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788822790248","product_condition":"new"},"df_price":12.9,"df_sale_price":"","df_regular_price":12.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/la-leggenda-di-ulisse-il-piu-furbo-di-tutti-gli-eroi-sara-prossomariti-newton-compton-editori-192x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/140837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=140837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/140835"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=140837"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=140837"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=140837"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=140837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}