{"id":139460,"date":"2024-11-09T14:03:09","date_gmt":"2024-11-09T13:03:09","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/"},"modified":"2026-03-14T00:50:31","modified_gmt":"2026-03-13T23:50:31","slug":"l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/","title":{"rendered":"l&#8217;ultimo miglio"},"content":{"rendered":"<p>Se la storia &egrave; un &ldquo;bene comune&rdquo;, allora &egrave; chiaro che quel bene va condiviso. Fanno bene i due autori a pubblicare questo libro, valido non solo per l&rsquo;avanzamento delle conoscenze nell&rsquo;ambito della storia militare, ma soprattutto perch&eacute; appare in un momento dominato dal &ldquo;presentismo&rdquo;. Questo futile fenomeno offusca il futuro, che invece si pu&ograve; schiarire attraverso i valori storici.<\/p>\n<p>Quel che accade fra le Eolie e il Golfo di Milazzo e che viene narrato in questo libro, d&agrave; sostanza, corpo e sangue, all&rsquo;articolo 11 della Costituzione del nostro Paese: &ldquo;L&rsquo;Italia ripudia la guerra come strumento di offesa alla libert&agrave; degli altri popoli e come mezzo di risoluzione delle controversie internazionali&rdquo;.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>la guerra tra milazzo e le isole eolie 1940-1943<\/p>\n<p class=\"autore\"><span>Author: <\/span>giuseppe pandolfo &#8211; salvo fagone<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>ibn editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788875653507<\/p>\n","protected":false},"featured_media":139458,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3051],"product_tag":[],"class_list":{"0":"post-139460","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-from-1919-to-1945","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>l&#039;ultimo miglio - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l&#039;ultimo miglio\" \/>\n<meta property=\"og:description\" content=\"Subtitle: la guerra tra milazzo e le isole eolie 1940-1943Author: giuseppe pandolfo - salvo fagonePublisher: ibn editoreISBN: 9788875653507\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:50:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-ultimo-miglio-la-guerra-tra-milazzo-e-le-isole-eolie-1940-1943-giuseppe-pandolfo-salvo-fagone-ibn-editore.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;23,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\\\/\",\"name\":\"l'ultimo miglio - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/l-ultimo-miglio-la-guerra-tra-milazzo-e-le-isole-eolie-1940-1943-giuseppe-pandolfo-salvo-fagone-ibn-editore.jpg\",\"datePublished\":\"2024-11-09T13:03:09+00:00\",\"dateModified\":\"2026-03-13T23:50:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/l-ultimo-miglio-la-guerra-tra-milazzo-e-le-isole-eolie-1940-1943-giuseppe-pandolfo-salvo-fagone-ibn-editore.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/l-ultimo-miglio-la-guerra-tra-milazzo-e-le-isole-eolie-1940-1943-giuseppe-pandolfo-salvo-fagone-ibn-editore.jpg\",\"width\":500,\"height\":748},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"l&#8217;ultimo miglio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"23.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788875653507\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"l'ultimo miglio - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"l'ultimo miglio","og_description":"Subtitle: la guerra tra milazzo e le isole eolie 1940-1943Author: giuseppe pandolfo - salvo fagonePublisher: ibn editoreISBN: 9788875653507","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:50:31+00:00","og_image":[{"width":500,"height":748,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-ultimo-miglio-la-guerra-tra-milazzo-e-le-isole-eolie-1940-1943-giuseppe-pandolfo-salvo-fagone-ibn-editore.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;23,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/","name":"l'ultimo miglio - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-ultimo-miglio-la-guerra-tra-milazzo-e-le-isole-eolie-1940-1943-giuseppe-pandolfo-salvo-fagone-ibn-editore.jpg","datePublished":"2024-11-09T13:03:09+00:00","dateModified":"2026-03-13T23:50:31+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-ultimo-miglio-la-guerra-tra-milazzo-e-le-isole-eolie-1940-1943-giuseppe-pandolfo-salvo-fagone-ibn-editore.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-ultimo-miglio-la-guerra-tra-milazzo-e-le-isole-eolie-1940-1943-giuseppe-pandolfo-salvo-fagone-ibn-editore.jpg","width":500,"height":748},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/l-ultimo-miglio-giuseppe-pandolfo-salvo-fagone-9788875653507\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"l&#8217;ultimo miglio"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"23.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788875653507","product_condition":"new"},"df_price":23,"df_sale_price":"","df_regular_price":23,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/l-ultimo-miglio-la-guerra-tra-milazzo-e-le-isole-eolie-1940-1943-giuseppe-pandolfo-salvo-fagone-ibn-editore-201x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/139460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=139460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/139458"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=139460"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=139460"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=139460"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=139460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}