{"id":139035,"date":"2024-10-30T16:22:11","date_gmt":"2024-10-30T15:22:11","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/"},"modified":"2026-03-14T00:51:19","modified_gmt":"2026-03-13T23:51:19","slug":"shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/","title":{"rendered":"shakespeare e il richiamo del mare"},"content":{"rendered":"<p>Si &egrave; sostenuto da parte di alcuni che <strong>William Shakespeare<\/strong> fosse nato in Italia o, almeno, che avesse origini italiane, ma questo &egrave; piuttosto comune con i grandi e con i grandissimi, tutti avvolti dal mistero della loro eccellenza e tutti contesi.<\/p>\n<p>Quel che si sa, al di l&agrave; di ogni ipotesi e di ogni dubbio, &egrave; che Shakespeare <strong>conosceva bene l&rsquo;Italia<\/strong> (forse per esperienza diretta, pi&ugrave; probabilmente grazie a racconti e a letture), che fa da sfondo a molte delle sue opere pi&ugrave; celebri, da <em>Romeo e Giulietta<\/em>, a <em>I due gentiluomini di Verona<\/em>, <em>Il mercante di Venezia<\/em>, <em>La bisbetica domata<\/em>. L&rsquo;Italia fa da ambientazione ai drammi storici, &egrave; interpretata da alcuni fra i suoi pi&ugrave; famosi personaggi, non di rado &egrave; addirittura descritta, eppure &ndash; fa notare Luigi Giannitrapani nel suo libro &ndash; la geografia italiana resta, per Shakespeare, una <em>geografia poetica<\/em>. Tanto pi&ugrave; evocativa e immaginaria, dunque, che reale.<\/p>\n<p>Prima ancora dei luoghi e delle tradizioni, di italiano <strong>nelle opere di Shakespeare c&rsquo;&egrave; il mare<\/strong>. Dando conto delle intenzioni che lo hanno guidato lungo la scrittura di questo libro, Luigi Giannitrapani, studioso di Shakespeare e Ufficiale di Marina, scrive: <em>Il mare &egrave; uno degli elementi naturali che Shakespeare adopera pi&ugrave; spesso, sia come scenario [&hellip;] che come allegoria della vita e delle passioni umane<\/em>.<\/p>\n<p>Come le passioni umane, di cui Shakespeare &egrave; interprete e descrittore sommo, il mare &egrave;<strong> imprevedibile, mutevole<\/strong>, mai si pu&ograve; essere certi di averlo sotto controllo. E se, nell&rsquo;opera di Shakespeare, le passioni umane sono dappertutto, egualmente accade, ci racconta questo libro, per il mare. <strong>Non c&rsquo;&egrave; Shakespeare senza lessico marinaro<\/strong>. Non c&rsquo;&egrave; Shakespeare senza il mare.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>luigi giannitrapani<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>serel international (stefano termanini editore)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788889401675<\/p>\n","protected":false},"featured_media":139037,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2983],"product_tag":[],"class_list":{"0":"post-139035","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-literary-essays","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>shakespeare e il richiamo del mare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"shakespeare e il richiamo del mare\" \/>\n<meta property=\"og:description\" content=\"Author: luigi giannitrapaniPublisher: serel international (stefano termanini editore)ISBN: 9788889401675\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:51:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-serel-international-stefano-termanini-editore-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"815\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;18,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\\\/\",\"name\":\"shakespeare e il richiamo del mare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-serel-international-stefano-termanini-editore-1.jpg\",\"datePublished\":\"2024-10-30T15:22:11+00:00\",\"dateModified\":\"2026-03-13T23:51:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-serel-international-stefano-termanini-editore-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-serel-international-stefano-termanini-editore-1.jpg\",\"width\":500,\"height\":815},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"shakespeare e il richiamo del mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"18.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788889401675\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"shakespeare e il richiamo del mare - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"shakespeare e il richiamo del mare","og_description":"Author: luigi giannitrapaniPublisher: serel international (stefano termanini editore)ISBN: 9788889401675","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:51:19+00:00","og_image":[{"width":500,"height":815,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-serel-international-stefano-termanini-editore-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;18,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/","name":"shakespeare e il richiamo del mare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-serel-international-stefano-termanini-editore-1.jpg","datePublished":"2024-10-30T15:22:11+00:00","dateModified":"2026-03-13T23:51:19+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-serel-international-stefano-termanini-editore-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-serel-international-stefano-termanini-editore-1.jpg","width":500,"height":815},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-9788889401675\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"shakespeare e il richiamo del mare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"18.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788889401675","product_condition":"new"},"df_price":18,"df_sale_price":"","df_regular_price":18,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/shakespeare-e-il-richiamo-del-mare-luigi-giannitrapani-serel-international-stefano-termanini-editore-1-184x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/139035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=139035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/139037"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=139035"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=139035"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=139035"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=139035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}