{"id":138952,"date":"2024-10-29T11:18:10","date_gmt":"2024-10-29T10:18:10","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/"},"modified":"2026-03-14T00:51:45","modified_gmt":"2026-03-13T23:51:45","slug":"come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/","title":{"rendered":"come vento tra le vele"},"content":{"rendered":"<p>&laquo;<em>Era facile invidiare quella bella coppia, facile innamorarsi di lui o di lei. Oppure di entrambi. Erano uno la met&agrave; dell&#8217;altro e insieme formavano un piccolo universo che poteva includere o escludere tutti gli altri. Gli antichi credevano che gli dei per invidia punissero gli umani che erano troppo felici. Ma pi&ugrave; forti degli dei, in questa storia vera, sono stati un veliero e una tigre, che hanno segnato il corso di un amore senza confini di spazio e di tempo.<\/em>&raquo;<\/p>\n<p><strong>Il veliero pi&ugrave; famoso al mondo, un affascinante comandante, una donna determinata: la storia vera di una passione senza tempo.<\/strong><\/p>\n<p><em>Lorenza Mel<\/em> e <em>Francesco Bottoni<\/em> s&#8217;incontrano per la prima volta sulla nave scuola Amerigo Vespucci e da quel momento non si lasciano pi&ugrave;. Lei &egrave; un&#8217;<strong>affermata avvocata veneziana<\/strong>, lui il <strong>vicecomandante del veliero simbolo per tutta la Marina Militare<\/strong>, ambasciatore dell&#8217;ingegno, dell&#8217;arte e della bellezza italiana nel mondo.<\/p>\n<p>Le loro vite si intrecciano tra venti favorevoli e tempeste improvvise, in un viaggio che li porta a scoprire il significato profondo della dedizione e della perseveranza. Quando a <em>Francesco <\/em>viene assegnato l&#8217;incarico di comandante del Vespucci, &egrave; la realizzazione di un sogno che lo consacra come uno dei personaggi pi&ugrave; rappresentativi e pi&ugrave; amati della Marina, grazie alla personalit&agrave; vulcanica, al coraggio e all&#8217;attenzione con cui si dedica alla formazione degli allievi imbarcati sulla nave. <strong><em>Lorenza<\/em>, nonostante i sacrifici e le rinunce, lo segue nei porti dove il veliero ormeggia ma spesso non pu&ograve; che attenderlo<\/strong>. Ed &egrave; a lei che il destino riserva la parte pi&ugrave; dolorosa e dura da affrontare. Dopo un periodo vissuto nella disperazione, che la conduce pericolosamente sull&#8217;orlo dell&#8217;abisso, ritrover&agrave; il suo amore grazie a un&#8217;inattesa alleata.<\/p>\n<p><strong>Un&#8217;appassionante storia vera<\/strong>, mirabilmente ricostruita e narrata dall&#8217;autrice che ha conosciuto entrambi i protagonisti.<\/p>\n<p>Con una prefazione dell&#8217;Ammiraglio Giuseppe Cavo Dragone.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>una storia di amore e coraggio sull&#8217;amerigo vespucci<\/p>\n<p class=\"autore\"><span>Author: <\/span>sibyl von der schulenburg<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>sperling &amp; kupfer<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788820080884<\/p>\n","protected":false},"featured_media":138950,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,3055],"product_tag":[],"class_list":{"0":"post-138952","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-miscellaneous","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>come vento tra le vele - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"come vento tra le vele\" \/>\n<meta property=\"og:description\" content=\"Subtitle: una storia di amore e coraggio sull&#039;amerigo vespucciAuthor: sibyl von der schulenburgPublisher: sperling &amp; kupferISBN: 9788820080884\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:51:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/come-vento-tra-le-vele-von-der-schulenburg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"769\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\\\/\",\"name\":\"come vento tra le vele - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/come-vento-tra-le-vele-von-der-schulenburg.jpg\",\"datePublished\":\"2024-10-29T10:18:10+00:00\",\"dateModified\":\"2026-03-13T23:51:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/come-vento-tra-le-vele-von-der-schulenburg.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/come-vento-tra-le-vele-von-der-schulenburg.jpg\",\"width\":500,\"height\":769},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"come vento tra le vele\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788820080884\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"come vento tra le vele - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"come vento tra le vele","og_description":"Subtitle: una storia di amore e coraggio sull'amerigo vespucciAuthor: sibyl von der schulenburgPublisher: sperling &amp; kupferISBN: 9788820080884","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:51:45+00:00","og_image":[{"width":500,"height":769,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/come-vento-tra-le-vele-von-der-schulenburg.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/","name":"come vento tra le vele - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/come-vento-tra-le-vele-von-der-schulenburg.jpg","datePublished":"2024-10-29T10:18:10+00:00","dateModified":"2026-03-13T23:51:45+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/come-vento-tra-le-vele-von-der-schulenburg.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/come-vento-tra-le-vele-von-der-schulenburg.jpg","width":500,"height":769},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/come-vento-tra-le-vele-sibyl-von-der-schulenburg-9788820080884\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"come vento tra le vele"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788820080884","product_condition":"new"},"df_price":19.9,"df_sale_price":"","df_regular_price":19.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/come-vento-tra-le-vele-von-der-schulenburg-195x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/138952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=138952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/138950"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=138952"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=138952"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=138952"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=138952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}