{"id":137257,"date":"2024-09-24T16:08:31","date_gmt":"2024-09-24T14:08:31","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/"},"modified":"2026-03-14T00:57:19","modified_gmt":"2026-03-13T23:57:19","slug":"large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/","title":{"rendered":"large lined notebook &#8220;no water &#8211; no life &#8211; no blue &#8211; no green&#8221; (ethical series)"},"content":{"rendered":"<p>100 sides <strong>large<\/strong> lined <strong>notebook <\/strong>in <em>Ecogreen<\/em> paper bound with a durable <strong>Singer stitch sewing<\/strong>, suitable for school use. <em>Ecogreen<\/em> is a 80 grams paper Made in Europe, made with <strong>100% recycled fibres<\/strong>, produced without the use of chlorine and optical brighteners. Given its relaxing <strong>white\/grey color<\/strong> and <strong>low transparency<\/strong>, it is particularly suitable for writing. <strong>The cover<\/strong>, however, is made of <em>EcoTerra<\/em>, a paper made with a <strong>mix of virgin and recycled fibers<\/strong> derived from annual plants, such as cotton and cellulose. <em>EcoTerra<\/em> is <strong>velvety to the touch<\/strong> and has a <strong>matte effect<\/strong>.<\/p>\n<p><strong>Alfabet<\/strong> is an <strong>ecological stationery shop<\/strong>, 100% Italian. For 30 years it has been working with <strong>recycled paper and eco-friendly materials<\/strong>. The artisanal creation of its products can be seen in the <strong>details of the finishes<\/strong>. Respect for the environment and work ethic are his daily mission. Choosing <em>Alfabet <\/em>means rewarding Made in Italy, respecting the environment by purchasing eco-compatible products and having <strong>practicality, quality and design<\/strong> in your hands.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>21&#215;29,7 cm<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>alfabet<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>8020994681780TER<\/p>\n","protected":false},"featured_media":137255,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2943],"product_tag":[],"class_list":{"0":"post-137257","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-notebooks","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>large lined notebook &quot;no water - no life - no blue - no green&quot; (ethical series) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"large lined notebook &quot;no water - no life - no blue - no green&quot; (ethical series)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 21x29,7 cmManufacturer: alfabetISBN: 8020994681780TER\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T23:57:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadernone-a-righe-no-water-no-life-no-blue-no-green-serie-ethical-alfabet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;6,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\\\/\",\"name\":\"large lined notebook \\\"no water - no life - no blue - no green\\\" (ethical series) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/quadernone-a-righe-no-water-no-life-no-blue-no-green-serie-ethical-alfabet.jpg\",\"datePublished\":\"2024-09-24T14:08:31+00:00\",\"dateModified\":\"2026-03-13T23:57:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/quadernone-a-righe-no-water-no-life-no-blue-no-green-serie-ethical-alfabet.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/quadernone-a-righe-no-water-no-life-no-blue-no-green-serie-ethical-alfabet.jpg\",\"width\":700,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"large lined notebook &#8220;no water &#8211; no life &#8211; no blue &#8211; no green&#8221; (ethical series)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"6.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"8020994681780TER\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"large lined notebook \"no water - no life - no blue - no green\" (ethical series) - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"large lined notebook \"no water - no life - no blue - no green\" (ethical series)","og_description":"Subtitle: 21x29,7 cmManufacturer: alfabetISBN: 8020994681780TER","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-13T23:57:19+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadernone-a-righe-no-water-no-life-no-blue-no-green-serie-ethical-alfabet.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;6,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/","name":"large lined notebook \"no water - no life - no blue - no green\" (ethical series) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadernone-a-righe-no-water-no-life-no-blue-no-green-serie-ethical-alfabet.jpg","datePublished":"2024-09-24T14:08:31+00:00","dateModified":"2026-03-13T23:57:19+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadernone-a-righe-no-water-no-life-no-blue-no-green-serie-ethical-alfabet.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadernone-a-righe-no-water-no-life-no-blue-no-green-serie-ethical-alfabet.jpg","width":700,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/large-lined-notebook-no-water-no-life-no-blue-no-green-ethical-series-8020994681780ter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"large lined notebook &#8220;no water &#8211; no life &#8211; no blue &#8211; no green&#8221; (ethical series)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"6.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"8020994681780TER","product_condition":"new"},"df_price":6,"df_sale_price":"","df_regular_price":6,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadernone-a-righe-no-water-no-life-no-blue-no-green-serie-ethical-alfabet-300x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/137257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=137257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/137255"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=137257"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=137257"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=137257"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=137257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}