{"id":126174,"date":"2024-07-10T16:38:35","date_gmt":"2024-07-10T14:38:35","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/tra-due-oceani-cristina-henriquez-9791255750284\/"},"modified":"2026-03-14T01:02:51","modified_gmt":"2026-03-14T00:02:51","slug":"tra-due-oceani-cristina-henriquez-9791255750284","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tra-due-oceani-cristina-henriquez-9791255750284\/","title":{"rendered":"tra due oceani"},"content":{"rendered":"<p><strong>Il Canale di Panama<\/strong> &egrave; passato alla storia come la pi&ugrave; grande impresa d&rsquo;ingegneria mai realizzata: dal 1907 la sua costruzione &egrave; durata sette anni e ha visto centinaia di persone da ogni parte del continente impegnate nell&rsquo;opera di unire due oceani, scavando nella terra per chilometri. Per <strong>Valentina e Francisco<\/strong> il canale &egrave; motivo di lotta, a lei toglieranno la casa, mentre lui teme la fine del suo lavoro di pescatore. Per il figlio di Francisco, <strong>Omar<\/strong>, &egrave; invece una speranza di autonomia e di una vita meno solitaria. Mentre per la giovane <strong>Ada Bunting<\/strong>, che &egrave; arrivata a Panama da Barbados, &egrave; la promessa di poter aiutare la sorella malata. Dall&rsquo;incrocio di queste traiettorie individuali, mentre i lavori procedono ridisegnando i confini e la storia, i protagonisti troveranno l&rsquo;occasione di rimodellare anche il proprio destino. Con umanit&agrave; e compassione, Cristina Henr&iacute;quez entra nel vivo della <strong>storia coloniale americana<\/strong> presentando <strong>la grande opera del canale<\/strong> come una frattura, che si specchia nelle vite degli ultimi: <strong>uomini e donne che hanno vissuto quel momento sulla propria pelle<\/strong>, amando, combattendo e immaginando insieme la possibilit&agrave; di un futuro diverso, un mondo pi&ugrave; grande, un miracolo di salvezza. Questo libro &egrave; per chi vede una mappa nelle linee della mano, per chi tiene in tasca una pietra portafortuna, per chi continua a credere nel potere della meraviglia e per chi si sente avvolto dall&rsquo;aria calda come una coperta, mentre affida al mare il ricordo della persona amata.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>cristina henriquez<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>enne enne editore (nne)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791255750284<\/p>\n","protected":false},"featured_media":126172,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2809],"product_tag":[],"class_list":{"0":"post-126174","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-novels","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>tra due oceani - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tra due oceani\" \/>\n<meta property=\"og:description\" content=\"Author: cristina henriquezPublisher: enne enne editore (nne)ISBN: 9791255750284\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tra-due-oceani-cristina-henriquez-9791255750284\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:02:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tra-due-oceani-cristina-henriquez-nneditore.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"785\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;20,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tra-due-oceani-cristina-henriquez-9791255750284\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tra-due-oceani-cristina-henriquez-9791255750284\\\/\",\"name\":\"tra due oceani - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tra-due-oceani-cristina-henriquez-9791255750284\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tra-due-oceani-cristina-henriquez-9791255750284\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/tra-due-oceani-cristina-henriquez-nneditore.jpg\",\"datePublished\":\"2024-07-10T14:38:35+00:00\",\"dateModified\":\"2026-03-14T00:02:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tra-due-oceani-cristina-henriquez-9791255750284\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tra-due-oceani-cristina-henriquez-9791255750284\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tra-due-oceani-cristina-henriquez-9791255750284\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/tra-due-oceani-cristina-henriquez-nneditore.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/tra-due-oceani-cristina-henriquez-nneditore.jpg\",\"width\":500,\"height\":785},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/tra-due-oceani-cristina-henriquez-9791255750284\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"tra due oceani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"20.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791255750284\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"tra due oceani - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"tra due oceani","og_description":"Author: cristina henriquezPublisher: enne enne editore (nne)ISBN: 9791255750284","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tra-due-oceani-cristina-henriquez-9791255750284\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:02:51+00:00","og_image":[{"width":500,"height":785,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tra-due-oceani-cristina-henriquez-nneditore.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;20,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tra-due-oceani-cristina-henriquez-9791255750284\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tra-due-oceani-cristina-henriquez-9791255750284\/","name":"tra due oceani - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tra-due-oceani-cristina-henriquez-9791255750284\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tra-due-oceani-cristina-henriquez-9791255750284\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tra-due-oceani-cristina-henriquez-nneditore.jpg","datePublished":"2024-07-10T14:38:35+00:00","dateModified":"2026-03-14T00:02:51+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tra-due-oceani-cristina-henriquez-9791255750284\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tra-due-oceani-cristina-henriquez-9791255750284\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tra-due-oceani-cristina-henriquez-9791255750284\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tra-due-oceani-cristina-henriquez-nneditore.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tra-due-oceani-cristina-henriquez-nneditore.jpg","width":500,"height":785},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/tra-due-oceani-cristina-henriquez-9791255750284\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"tra due oceani"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"20.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9791255750284","product_condition":"new"},"df_price":20,"df_sale_price":"","df_regular_price":20,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/tra-due-oceani-cristina-henriquez-nneditore-191x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/126174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=126174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/126172"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=126174"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=126174"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=126174"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=126174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}