{"id":118658,"date":"2024-05-23T17:42:26","date_gmt":"2024-05-23T15:42:26","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/"},"modified":"2026-03-14T01:09:03","modified_gmt":"2026-03-14T00:09:03","slug":"quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/","title":{"rendered":"quadro &#8220;figure eight double knot \/ otto ripassato&#8221;"},"content":{"rendered":"<p><strong>Dettaglio <\/strong>su <em><strong>Figure eight double knot<\/strong><\/em> del poster &ldquo;<em><strong>20 essential knots<\/strong><\/em>&ldquo;.<\/p>\n<p><strong>Cornice in legno bianca opaca e plexiglass.<\/strong><\/p>\n<p>Stampa Indigo su <strong>carta Fedrigoni<\/strong> 300 g con <strong>passepartout<\/strong>.<\/p>\n<p><strong>Logo in rilievo stampato a mano.<\/strong><\/p>\n<p><em><strong>Addvent <\/strong><\/em>&egrave; un progetto di <em>Colab<\/em>, un team internazionale di <strong>giovani professionisti<\/strong> con meno di 35 anni, <strong>un incontro di visioni e di storie<\/strong> accomunate da talento, passione e da un briciolo di follia, che si sono incrociate nel pieno della pandemia del 2020.<\/p>\n<p>Sono <strong>un team di illustratori, creativi e designers<\/strong>, che vogliono scoprire e <strong>raccontare il mondo che li circonda<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 33&#215;23<\/p>\n<p class=\"autore\"><span>Author: <\/span>chiara giusti<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>addvent<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1716478945<\/p>\n","protected":false},"featured_media":145414,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2442],"product_tag":[],"class_list":{"0":"post-118658","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-knots-framework","7":"product_shipping_class-packaging","9":"first","10":"onbackorder","11":"sale","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>quadro &quot;figure eight double knot \/ otto ripassato&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"quadro &quot;figure eight double knot \/ otto ripassato&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 33x23Author: chiara giustiManufacturer: addventISBN: LDM1716478945\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:09:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadro-figure-eight-double-knot-otto-ripassato-giusti-addvent.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"933\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\\\/\",\"name\":\"quadro \\\"figure eight double knot \\\/ otto ripassato\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/quadro-figure-eight-double-knot-otto-ripassato-giusti-addvent.jpg\",\"datePublished\":\"2024-05-23T15:42:26+00:00\",\"dateModified\":\"2026-03-14T00:09:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/quadro-figure-eight-double-knot-otto-ripassato-giusti-addvent.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/quadro-figure-eight-double-knot-otto-ripassato-giusti-addvent.jpg\",\"width\":933,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"quadro &#8220;figure eight double knot \\\/ otto ripassato&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1716478945\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"quadro \"figure eight double knot \/ otto ripassato\" - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"quadro \"figure eight double knot \/ otto ripassato\"","og_description":"Subtitle: cm 33x23Author: chiara giustiManufacturer: addventISBN: LDM1716478945","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:09:03+00:00","og_image":[{"width":933,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadro-figure-eight-double-knot-otto-ripassato-giusti-addvent.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/","name":"quadro \"figure eight double knot \/ otto ripassato\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadro-figure-eight-double-knot-otto-ripassato-giusti-addvent.jpg","datePublished":"2024-05-23T15:42:26+00:00","dateModified":"2026-03-14T00:09:03+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadro-figure-eight-double-knot-otto-ripassato-giusti-addvent.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadro-figure-eight-double-knot-otto-ripassato-giusti-addvent.jpg","width":933,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/quadro-figure-eight-double-knot-otto-ripassato-chiara-giusti-ldm1716478945\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"quadro &#8220;figure eight double knot \/ otto ripassato&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"LDM1716478945","product_condition":"new"},"df_price":14,"df_sale_price":14,"df_regular_price":28,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/quadro-figure-eight-double-knot-otto-ripassato-giusti-addvent-300x225.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/118658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=118658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/145414"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=118658"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=118658"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=118658"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=118658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}