{"id":116949,"date":"2024-04-09T16:02:21","date_gmt":"2024-04-09T14:02:21","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/"},"modified":"2026-03-14T01:14:01","modified_gmt":"2026-03-14T00:14:01","slug":"storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/","title":{"rendered":"storie fantastiche di isole vere"},"content":{"rendered":"<p><strong>Isole contese, abbandonate, conquistate e riconquistate, vendute e amate, incantate e stregate, plasmate dal vento che le abbraccia e le sferza, luoghi dell&rsquo;origine e dell&rsquo;utopia, inaccessibili, invisibili, isole che non sono isole, appena affioranti, quasi penisole<\/strong>: da Cipro ad Alcatraz, da Tortuga alle Gal&aacute;pagos, quando parliamo di isole &ndash; secondo il narratore di questo libro &ndash; parliamo di profezie, messaggi in bottiglia affidati alle acque. Che cosa vogliono comunicarci, le isole, con la loro presunzione di pensarsi come centro del mondo, di credere che tutto giri attorno a loro, come in realt&agrave; fanno solo le correnti e i pesci? <strong>La cosa pi&uacute; difficile di fronte a un&rsquo;isola &egrave; semplicemente leggerla<\/strong>, capire quale lingua parla e quale inesauribile racconto mormora il mare frangendosi sugli scogli.<\/p>\n<p><strong><em>Storie fantastiche di isole vere<\/em> descrive l&rsquo;incontro di due personaggi<\/strong>. <strong>Il primo &egrave; un narratore, il Pilota, un marinaio<\/strong> che ha navigato su ogni rotta ed &egrave; sbarcato in ogni porto, e <strong>possiede perci&ograve; la saggezza dell&rsquo;esperienza, quella vera, che si deposita lentamente nel corso di una vita<\/strong>. Sorseggiando un bicchiere di vino Pigato o di rum, fumando una delle sue sigarette papier ma&iuml;s, pescando nella baia a bordo di una lampara o osservando il mare dall&rsquo;alto della collina, con il suo affabulare ipnotico e avvolgente <strong>il Pilota irretisce chi lo ascolta, lo piglia all&rsquo;amo, lo cattura, iniziandolo all&rsquo;insulomania<\/strong>, il culto, o malattia, degli ultimi discendenti di Atlantide.<\/p>\n<p><strong>Il secondo personaggio si limita per lo pi&uacute; ad accogliere e raccogliere i racconti dell&rsquo;altro, ma senza chi ascolta non esisterebbe chi narra, senza lettore non ci sarebbe scrittore<\/strong>. Il porto in cui i due si trovano &egrave; quello di Genova, dove <em>&laquo;quando vedi una nave enorme sfilare piano in fondo alle vie, ti chiedi se sta salpando lei o se sta salpando la citt&agrave;&raquo;<\/em>; il molo su cui passeggiano &egrave; &laquo;<em>una rampa verso l&rsquo;ignoto, una macchina della fantasia: se non salpi con una nave, lo fai con il desiderio o con i ricordi <\/em>&raquo;. E <strong>il testo che compongono insieme &egrave; un isolario<\/strong>, ovvero un libro anfibio, per met&agrave; vero e per met&agrave; fantastico: un inno al mistero e all&rsquo;inquieta bellezza delle isole, e quindi all&rsquo;arte del racconto, e all&rsquo;oceano delle storie.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>ernesto franco<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>giulio einaudi editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788806263928<\/p>\n","protected":false},"featured_media":116947,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2809],"product_tag":[],"class_list":{"0":"post-116949","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-novels","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>storie fantastiche di isole vere - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"storie fantastiche di isole vere\" \/>\n<meta property=\"og:description\" content=\"Author: ernesto francoPublisher: giulio einaudi editoreISBN: 9788806263928\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:14:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storie-fantastiche-di-isole-vere-franco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"794\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;17,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\\\/\",\"name\":\"storie fantastiche di isole vere - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storie-fantastiche-di-isole-vere-franco.jpg\",\"datePublished\":\"2024-04-09T14:02:21+00:00\",\"dateModified\":\"2026-03-14T00:14:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storie-fantastiche-di-isole-vere-franco.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/storie-fantastiche-di-isole-vere-franco.jpg\",\"width\":500,\"height\":794},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"storie fantastiche di isole vere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"17.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788806263928\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"storie fantastiche di isole vere - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"storie fantastiche di isole vere","og_description":"Author: ernesto francoPublisher: giulio einaudi editoreISBN: 9788806263928","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:14:01+00:00","og_image":[{"width":500,"height":794,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storie-fantastiche-di-isole-vere-franco.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;17,50","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/","name":"storie fantastiche di isole vere - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storie-fantastiche-di-isole-vere-franco.jpg","datePublished":"2024-04-09T14:02:21+00:00","dateModified":"2026-03-14T00:14:01+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storie-fantastiche-di-isole-vere-franco.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storie-fantastiche-di-isole-vere-franco.jpg","width":500,"height":794},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/storie-fantastiche-di-isole-vere-ernesto-franco-9788806263928\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"storie fantastiche di isole vere"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"17.50","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788806263928","product_condition":"new"},"df_price":17.5,"df_sale_price":"","df_regular_price":17.5,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/storie-fantastiche-di-isole-vere-franco-189x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/116949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=116949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/116947"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=116949"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=116949"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=116949"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=116949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}