{"id":115819,"date":"2024-03-16T18:25:37","date_gmt":"2024-03-16T17:25:37","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/"},"modified":"2026-03-14T01:17:29","modified_gmt":"2026-03-14T00:17:29","slug":"non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/","title":{"rendered":"non puoi fermare l&#8217;onda"},"content":{"rendered":"<p>Una storia di <strong>amicizia, speranza e lotta per l&rsquo;emancipazione<\/strong>. Un romanzo per ragazzi e ragazze appassionati di <strong>sport<\/strong> in cerca di una storia che racconti le battaglie dei giovani di oggi.<\/p>\n<p><strong>Sahanya aveva dodici anni <\/strong>quando il cugino le diede una tavola e le insegn&ograve; a <strong>surfare<\/strong>. Dopo anni passati a cucire, riordinare la casa e cucinare per il fratello, la ragazza non ha dimenticato le emozioni provate quella volta, il richiamo delle onde, <strong>la sensazione di libert&agrave;<\/strong>. Ma <strong>nel suo piccolo villaggio il surf &egrave; proibito alle donne<\/strong>; il fratello non le ha pi&ugrave; permesso di praticarlo, perch&eacute; violare questo tab&ugrave; attirerebbe sulla loro famiglia una grande vergogna. Meglio allora lasciare quell&rsquo;esperienza tra i ricordi e non pensarci pi&ugrave;. Le cose, per&ograve;, cambiano quando <strong>una donna americana si trasferisce di fronte a casa sua<\/strong>. Carol &egrave; intraprendente e sicura e vede la passione ardere negli occhi di Sahanya, quando le parla del surf. Le propone di portarla con s&eacute; tra le onde, all&rsquo;alba, quando nessuno le vedr&agrave;. Sar&agrave; l&rsquo;inizio di <strong>una rivolta silenziosa<\/strong>, per Sahanya e per le altre ragazze di Arugam Bay, alla <strong>conquista del diritto alla felicit&agrave;<\/strong>.<\/p>\n<p>Et&agrave;: 12+<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>luca cognolato &#8211; silvia del francia<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>einaudi ragazzi (edizioni el)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788866568247<\/p>\n","protected":false},"featured_media":115817,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2610],"product_tag":[],"class_list":{"0":"post-115819","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-12-anni-children-and-young-adults","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>non puoi fermare l&#039;onda - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"non puoi fermare l&#039;onda\" \/>\n<meta property=\"og:description\" content=\"Author: luca cognolato - silvia del franciaPublisher: einaudi ragazzi (edizioni el)ISBN: 9788866568247\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:17:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-einaudi-ragazzi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"511\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;12,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\\\/\",\"name\":\"non puoi fermare l'onda - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-einaudi-ragazzi.jpg\",\"datePublished\":\"2024-03-16T17:25:37+00:00\",\"dateModified\":\"2026-03-14T00:17:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-einaudi-ragazzi.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-einaudi-ragazzi.jpg\",\"width\":511,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"non puoi fermare l&#8217;onda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"12.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788866568247\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"non puoi fermare l'onda - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"non puoi fermare l'onda","og_description":"Author: luca cognolato - silvia del franciaPublisher: einaudi ragazzi (edizioni el)ISBN: 9788866568247","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:17:29+00:00","og_image":[{"width":511,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-einaudi-ragazzi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;12,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/","name":"non puoi fermare l'onda - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-einaudi-ragazzi.jpg","datePublished":"2024-03-16T17:25:37+00:00","dateModified":"2026-03-14T00:17:29+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-einaudi-ragazzi.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-einaudi-ragazzi.jpg","width":511,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-9788866568247\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"non puoi fermare l&#8217;onda"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"12.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788866568247","product_condition":"new"},"df_price":12,"df_sale_price":"","df_regular_price":12,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/non-puoi-fermare-l-onda-luca-cognolato-silvia-del-francia-einaudi-ragazzi-219x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/115819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=115819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/115817"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=115819"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=115819"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=115819"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=115819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}