{"id":113431,"date":"2024-01-30T16:50:38","date_gmt":"2024-01-30T15:50:38","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/le-barche-perdute-antonello-pistoia-9791221045949\/"},"modified":"2026-03-14T01:22:47","modified_gmt":"2026-03-14T00:22:47","slug":"le-barche-perdute-antonello-pistoia-9791221045949","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-barche-perdute-antonello-pistoia-9791221045949\/","title":{"rendered":"le barche perdute"},"content":{"rendered":"<p>Dall&#8217;introduzione dell&#8217;autore:&nbsp;<em>[&#8230;] <\/em><em>Ho sentito la necessit&agrave; di ri-ordinare, ripercorrere la mia esperienza, di ri-viverla attraverso una narrazione fatta di immagini, di parole chiave che evocano ci&ograve; che ha reso avventurosa la mia vita di architetto e che rendono manifesto il mio viaggio emozionale interiore.<\/em><\/p>\n<p><em>[&#8230;] era il 1989, e da quel momento ho capito che mi piaceva lavorare, sentirmi coinvolto, trasportato, mosso nel recupero di imbarcazioni da lavoro destinate al disarmo.<\/em><\/p>\n<p><em>Barche che hanno un&#8217;anima, che la manifestano in ogni parte, nello scafo, nelle attrezzature, nei dettagli costruttivi. [&#8230;]<\/em><\/p>\n<p><em>In tutti questi anni di refitting ho capito, in modo sempre pi&ugrave; nitido, quanto sia importante mantenere questo spirito, questa vita, questa energia, perch&eacute; una volta rimossa, allontanata, non torna pi&ugrave;, si trasforma, si perde. [&#8230;]<\/em><\/p>\n<p><em>Per questo ho sempre cercato di mantenere in vita il pi&ugrave; possibile quello che c&#8217;era e mantenere lo spirito originario, l&#8217;identit&agrave; originaria. [&#8230;]<\/em><\/p>\n<p><em>Ho inseguito il dettaglio in modo maniacale, quasi un&#8217;ossessione che mi galoppava dentro ed ho cercato per quanto possibile di proteggere le mie idee guida, i principi, sia in ambito architettonico sia nell&#8217;<\/em>interior design<em>. [&#8230;]<\/em><\/p>\n<p><em>E&#8217; sempre un&#8217;impresa ardua dar voce alle proprie passioni, spiegare come sono nate, cosa significano, come si coltivano, trasmettere&nbsp;<\/em>quel non so che<em> che per noi &egrave; unico e irripetibile.<\/em><\/p>\n<p><em>Mi affido per questo alle tante immagini che di questo viaggio sono testimonianza, con la cura e la perizia che ho sempre dedicato a questa mia attivit&agrave;, nella speranza di trasmettere&nbsp;<\/em>quel che non so che<em> [&#8230;].<\/em><\/p>\n<p><strong>Prefazione di Giobbe Covatta.<\/strong><\/p>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>una storia di studi e progetti nautici<\/p>\n<p class=\"autore\"><span>Author: <\/span>antonello pistoia<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>antonello pistoia design<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791221045949<\/p>\n","protected":false},"featured_media":127477,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,2784,2788,3007],"product_tag":[],"class_list":{"0":"post-113431","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-boat-building","8":"product_cat-tiger-shark","9":"product_cat-monographs","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>le barche perdute - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"le barche perdute\" \/>\n<meta property=\"og:description\" content=\"Subtitle: una storia di studi e progetti nauticiAuthor: antonello pistoiaPublisher: antonello pistoia designISBN: 9791221045949\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-barche-perdute-antonello-pistoia-9791221045949\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:22:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/le-barche-perdute-una-storia-di-studi-e-progetti-nautici-antonello-pistoia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"506\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-barche-perdute-antonello-pistoia-9791221045949\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-barche-perdute-antonello-pistoia-9791221045949\\\/\",\"name\":\"le barche perdute - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-barche-perdute-antonello-pistoia-9791221045949\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-barche-perdute-antonello-pistoia-9791221045949\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/le-barche-perdute-una-storia-di-studi-e-progetti-nautici-antonello-pistoia-1.jpg\",\"datePublished\":\"2024-01-30T15:50:38+00:00\",\"dateModified\":\"2026-03-14T00:22:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-barche-perdute-antonello-pistoia-9791221045949\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-barche-perdute-antonello-pistoia-9791221045949\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-barche-perdute-antonello-pistoia-9791221045949\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/le-barche-perdute-una-storia-di-studi-e-progetti-nautici-antonello-pistoia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/le-barche-perdute-una-storia-di-studi-e-progetti-nautici-antonello-pistoia-1.jpg\",\"width\":506,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/le-barche-perdute-antonello-pistoia-9791221045949\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"le barche perdute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791221045949\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"le barche perdute - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"le barche perdute","og_description":"Subtitle: una storia di studi e progetti nauticiAuthor: antonello pistoiaPublisher: antonello pistoia designISBN: 9791221045949","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-barche-perdute-antonello-pistoia-9791221045949\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:22:47+00:00","og_image":[{"width":506,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/le-barche-perdute-una-storia-di-studi-e-progetti-nautici-antonello-pistoia-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-barche-perdute-antonello-pistoia-9791221045949\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-barche-perdute-antonello-pistoia-9791221045949\/","name":"le barche perdute - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-barche-perdute-antonello-pistoia-9791221045949\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-barche-perdute-antonello-pistoia-9791221045949\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/le-barche-perdute-una-storia-di-studi-e-progetti-nautici-antonello-pistoia-1.jpg","datePublished":"2024-01-30T15:50:38+00:00","dateModified":"2026-03-14T00:22:47+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-barche-perdute-antonello-pistoia-9791221045949\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-barche-perdute-antonello-pistoia-9791221045949\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-barche-perdute-antonello-pistoia-9791221045949\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/le-barche-perdute-una-storia-di-studi-e-progetti-nautici-antonello-pistoia-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/le-barche-perdute-una-storia-di-studi-e-progetti-nautici-antonello-pistoia-1.jpg","width":506,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/le-barche-perdute-antonello-pistoia-9791221045949\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"le barche perdute"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9791221045949","product_condition":"new"},"df_price":19,"df_sale_price":"","df_regular_price":19,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/le-barche-perdute-una-storia-di-studi-e-progetti-nautici-antonello-pistoia-1-217x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/113431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=113431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/127477"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=113431"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=113431"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=113431"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=113431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}