{"id":110503,"date":"2023-11-26T15:40:07","date_gmt":"2023-11-26T14:40:07","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/"},"modified":"2026-03-14T01:29:00","modified_gmt":"2026-03-14T00:29:00","slug":"25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/","title":{"rendered":"25 pesci da avvistare nel mediterraneo"},"content":{"rendered":"<p>Il <em><strong>Mediterraneo<\/strong><\/em>, con oltre 17.000 specie, &egrave; un <strong>mare di straordinaria bellezza e ricchezza di biodiversit&agrave;<\/strong>. Il poster illustra alcuni tra i <strong>pesci pi&ugrave; comuni che si possono incontrare e sfiorare<\/strong> facendo immersioni a diverse profondit&agrave;.<\/p>\n<p>Questo poster illustra i seguenti <strong>25 pesci del Mediterraneo<\/strong>:<\/p>\n<ul>\n<li>Aguglia<\/li>\n<li>Barracuda<\/li>\n<li>Dentice<\/li>\n<li>Sardina<\/li>\n<li>Spigola<\/li>\n<li>Occhiata<\/li>\n<li>Boga<\/li>\n<li>Orata<\/li>\n<li>Cefalo<\/li>\n<li>Razza<\/li>\n<li>Salpa<\/li>\n<li>Ombrina<\/li>\n<li>Castagnola<\/li>\n<li>Sarago<\/li>\n<li>Mormora<\/li>\n<li>Scorfano<\/li>\n<li>Tordo pavone<\/li>\n<li>Triglia<\/li>\n<li>Sciarrano<\/li>\n<li>Donzella<\/li>\n<li>Cicerello<\/li>\n<li>Sogliola<\/li>\n<li>Bavosa<\/li>\n<li>Rombo<\/li>\n<li>Ghiozzo<\/li>\n<\/ul>\n<p>Stampa Indigo su <strong>carta Fedrigoni<\/strong> 300 g con <strong>passepartout<\/strong>.<\/p>\n<p><strong>Logo in rilievo stampato a mano.<\/strong><\/p>\n<p><em><strong>Addvent <\/strong><\/em>&egrave; un progetto di <em>Colab<\/em>, un team internazionale di <strong>giovani professionisti<\/strong> con meno di 35 anni, un <strong>incontro di visioni e di storie<\/strong> accomunate da talento, passione e da un briciolo di follia, che si sono incrociate nel pieno della pandemia del 2020.<\/p>\n<p>Sono <strong>un team di illustratori, creativi e designers<\/strong>, che vogliono scoprire e <strong>raccontare il mondo che li circonda<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 40&#215;50<\/p>\n<p class=\"autore\"><span>Author: <\/span>elena domenichini<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>addvent<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1701009603<\/p>\n","protected":false},"featured_media":139476,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2428],"product_tag":[],"class_list":{"0":"post-110503","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-marine-biology-modern-prints","8":"first","9":"onbackorder","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>25 pesci da avvistare nel mediterraneo - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"25 pesci da avvistare nel mediterraneo\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 40x50Author: elena domenichiniManufacturer: addventISBN: LDM1701009603\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:29:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/25-pesci-da-avvistare-nel-mediterraneo-domenichini-addvent-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"552\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;22,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\\\/\",\"name\":\"25 pesci da avvistare nel mediterraneo - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/25-pesci-da-avvistare-nel-mediterraneo-domenichini-addvent-1.jpg\",\"datePublished\":\"2023-11-26T14:40:07+00:00\",\"dateModified\":\"2026-03-14T00:29:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/25-pesci-da-avvistare-nel-mediterraneo-domenichini-addvent-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/25-pesci-da-avvistare-nel-mediterraneo-domenichini-addvent-1.jpg\",\"width\":552,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"25 pesci da avvistare nel mediterraneo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"22.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1701009603\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"25 pesci da avvistare nel mediterraneo - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"25 pesci da avvistare nel mediterraneo","og_description":"Subtitle: cm 40x50Author: elena domenichiniManufacturer: addventISBN: LDM1701009603","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:29:00+00:00","og_image":[{"width":552,"height":700,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/25-pesci-da-avvistare-nel-mediterraneo-domenichini-addvent-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;22,50","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/","name":"25 pesci da avvistare nel mediterraneo - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/25-pesci-da-avvistare-nel-mediterraneo-domenichini-addvent-1.jpg","datePublished":"2023-11-26T14:40:07+00:00","dateModified":"2026-03-14T00:29:00+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/25-pesci-da-avvistare-nel-mediterraneo-domenichini-addvent-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/25-pesci-da-avvistare-nel-mediterraneo-domenichini-addvent-1.jpg","width":552,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/25-pesci-da-avvistare-nel-mediterraneo-elena-domenichini-ldm1701009603\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"25 pesci da avvistare nel mediterraneo"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"22.50","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"LDM1701009603","product_condition":"new"},"df_price":22.5,"df_sale_price":22.5,"df_regular_price":45,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/25-pesci-da-avvistare-nel-mediterraneo-domenichini-addvent-1-237x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/110503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=110503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/139476"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=110503"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=110503"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=110503"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=110503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}