{"id":109803,"date":"2023-11-07T15:32:49","date_gmt":"2023-11-07T14:32:49","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/"},"modified":"2026-03-14T01:31:08","modified_gmt":"2026-03-14T00:31:08","slug":"il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/","title":{"rendered":"il mio puzzle di lupo &#8211; l&#8217;oceano"},"content":{"rendered":"<p>Divertiti a comporre il fantastico <strong>puzzle da 54 pezzi<\/strong>!<\/p>\n<p>Sul retro del poster, <strong>cerca i 30 elementi da ritrovare sul puzzle<\/strong>.<\/p>\n<p>Leggi le avventure di Lupo nel libro <em>Il lupo che sognava il mare<\/em>, che trovi incluso nella valigetta!<\/p>\n<p>Et&agrave;: <strong>3+<\/strong><\/p>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>orianne lallemand &#8211; eleonore thuillier<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>gribaudo &#8211; if &#8211; idee editoriali feltrinelli (giangiacomo feltrinelli editore)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788858047484<\/p>\n","protected":false},"featured_media":124336,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2937,2614],"product_tag":[],"class_list":{"0":"post-109803","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-children","7":"product_cat-illustrated-books-and-fiction","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>il mio puzzle di lupo - l&#039;oceano - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"il mio puzzle di lupo - l&#039;oceano\" \/>\n<meta property=\"og:description\" content=\"Author: orianne lallemand - eleonore thuillierPublisher: gribaudo - if - idee editoriali feltrinelli (giangiacomo feltrinelli editore)ISBN: 9788858047484\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:31:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mio-puzzle-di-lupo-l-oceano-gribaudo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\\\/\",\"name\":\"il mio puzzle di lupo - l'oceano - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/mio-puzzle-di-lupo-l-oceano-gribaudo-1.jpg\",\"datePublished\":\"2023-11-07T14:32:49+00:00\",\"dateModified\":\"2026-03-14T00:31:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/mio-puzzle-di-lupo-l-oceano-gribaudo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/mio-puzzle-di-lupo-l-oceano-gribaudo-1.jpg\",\"width\":500,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"il mio puzzle di lupo &#8211; l&#8217;oceano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788858047484\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"il mio puzzle di lupo - l'oceano - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"il mio puzzle di lupo - l'oceano","og_description":"Author: orianne lallemand - eleonore thuillierPublisher: gribaudo - if - idee editoriali feltrinelli (giangiacomo feltrinelli editore)ISBN: 9788858047484","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:31:08+00:00","og_image":[{"width":500,"height":865,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mio-puzzle-di-lupo-l-oceano-gribaudo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/","name":"il mio puzzle di lupo - l'oceano - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mio-puzzle-di-lupo-l-oceano-gribaudo-1.jpg","datePublished":"2023-11-07T14:32:49+00:00","dateModified":"2026-03-14T00:31:08+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mio-puzzle-di-lupo-l-oceano-gribaudo-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mio-puzzle-di-lupo-l-oceano-gribaudo-1.jpg","width":500,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/il-mio-puzzle-di-lupo-l-oceano-orianne-lallemand-eleonore-thuillier-9788858047484\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"il mio puzzle di lupo &#8211; l&#8217;oceano"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788858047484","product_condition":"new"},"df_price":19.9,"df_sale_price":"","df_regular_price":19.9,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/mio-puzzle-di-lupo-l-oceano-gribaudo-1-173x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/109803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=109803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/124336"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=109803"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=109803"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=109803"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=109803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}