{"id":109685,"date":"2023-11-03T18:07:34","date_gmt":"2023-11-03T17:07:34","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/lo-stato-del-mare-tabitha-lasley-9788831912068\/"},"modified":"2026-03-14T01:31:40","modified_gmt":"2026-03-14T00:31:40","slug":"lo-stato-del-mare-tabitha-lasley-9788831912068","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lo-stato-del-mare-tabitha-lasley-9788831912068\/","title":{"rendered":"lo stato del mare"},"content":{"rendered":"<p><strong>Un memoir brutalmente onesto <\/strong>che fa luce su ci&ograve; che accade quando il desiderio femminile entra in conflitto con una cultura della mascolinit&agrave; in crisi.<\/p>\n<p>Da poco libera da una relazione tossica e sulla trentina, <strong>Tabitha Lasley<\/strong> ha lasciato il lavoro in una rivista londinese, fatto le valigie e investito i suoi risparmi in un contratto d&rsquo;affitto di sei mesi per un appartamento <strong>ad Aberdeen, in Scozia<\/strong>. Era decisa a portare finalmente a termine l&rsquo;idea a lungo rinviata di <strong>un libro sulle piattaforme petrolifere <\/strong>e gli uomini che ci lavorano. Perch&eacute; le piattaforme petrolifere? <em>Volevo vedere come sono gli uomini quando non hanno donne intorno<\/em>.<\/p>\n<p>Ad Aberdeen, Tabitha viene inghiottita dal mondo della manovalanza dell&rsquo;<strong>industria petrolifera<\/strong>, una vivida sottocultura piena di<strong> risse, duro lavoro, competizione e amicizie <\/strong>di straordinaria profondit&agrave;. Pi&ugrave; resta, pi&ugrave; scopre che la sua presenza ha un effetto destabilizzante sugli uomini&hellip;e su se stessa.<\/p>\n<p><em>Lo stato del mare<\/em> &egrave; il ritratto di un&rsquo;industria in declino: <em>offshore<\/em>&nbsp;&egrave; <strong>uno stile di vita<\/strong> per generazioni di uomini principalmente <strong>della classe operaia<\/strong>, ma anche una potente metafora per quegli aspetti della vita che cerchiamo di ignorare come<strong> la classe, la mascolinit&agrave;, i compromessi <\/strong>indotti dal desiderio e le terribili insidie di una via in salita che potrebbe, se ci sforzassimo abbastanza, portarci alla sicurezza.<\/p>\n<p>Questo libro &egrave; anche <strong>la storia di una giornalista<\/strong> la cui distanza professionale dal suo soggetto diventa pericolosamente sottile. Ad Aberdeen, quando non &egrave; impegnata nelle ricerche per il libro, <strong>Tabitha si ubriaca e balla<\/strong> lasciandosi andare, e <strong>rivive la sua giovinezza<\/strong>, quando la musica era buona e i ragazzi erano cattivi. Vent&rsquo;anni dopo, c&rsquo;&egrave; <strong>Caden: un operaio sposato<\/strong> che trascorre tre settimane sulle piattaforme e tre a riposo. Sola e in uno stato sempre pi&ugrave; precario, Tabitha si tuffa nella loro crescente attrazione. La <strong>relazione<\/strong>, <strong>incosciente e rischiosa<\/strong>, metter&agrave; a nudo entrambi.<\/p>\n<p><strong>La traduzione in italiano &egrave; curata da Raffaella Menichini<\/strong>, giornalista e traduttrice.<\/p>\n<p><strong>Tra i migliori libri dell&#8217;anno per il Guardian e Rivista Studio.<\/strong><\/p>\n<p><strong>Finalista per il Gordon Burn Prize e il Portico Prize 2022.<\/strong><\/p>\n<p>Edizione: 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>tabitha lasley<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>nr edizioni<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788831912068<\/p>\n","protected":false},"featured_media":144899,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803],"product_tag":[],"class_list":{"0":"post-109685","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>lo stato del mare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"lo stato del mare\" \/>\n<meta property=\"og:description\" content=\"Author: tabitha lasleyPublisher: nr edizioniISBN: 9788831912068\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lo-stato-del-mare-tabitha-lasley-9788831912068\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:31:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lo-stato-del-mare-tabitha-lasley-nr-edizioni-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;18,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lo-stato-del-mare-tabitha-lasley-9788831912068\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lo-stato-del-mare-tabitha-lasley-9788831912068\\\/\",\"name\":\"lo stato del mare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lo-stato-del-mare-tabitha-lasley-9788831912068\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lo-stato-del-mare-tabitha-lasley-9788831912068\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lo-stato-del-mare-tabitha-lasley-nr-edizioni-1.jpg\",\"datePublished\":\"2023-11-03T17:07:34+00:00\",\"dateModified\":\"2026-03-14T00:31:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lo-stato-del-mare-tabitha-lasley-9788831912068\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lo-stato-del-mare-tabitha-lasley-9788831912068\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lo-stato-del-mare-tabitha-lasley-9788831912068\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lo-stato-del-mare-tabitha-lasley-nr-edizioni-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/lo-stato-del-mare-tabitha-lasley-nr-edizioni-1.jpg\",\"width\":500,\"height\":754},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/lo-stato-del-mare-tabitha-lasley-9788831912068\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"lo stato del mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"18.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788831912068\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"lo stato del mare - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"lo stato del mare","og_description":"Author: tabitha lasleyPublisher: nr edizioniISBN: 9788831912068","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lo-stato-del-mare-tabitha-lasley-9788831912068\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:31:40+00:00","og_image":[{"width":500,"height":754,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lo-stato-del-mare-tabitha-lasley-nr-edizioni-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;18,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lo-stato-del-mare-tabitha-lasley-9788831912068\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lo-stato-del-mare-tabitha-lasley-9788831912068\/","name":"lo stato del mare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lo-stato-del-mare-tabitha-lasley-9788831912068\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lo-stato-del-mare-tabitha-lasley-9788831912068\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lo-stato-del-mare-tabitha-lasley-nr-edizioni-1.jpg","datePublished":"2023-11-03T17:07:34+00:00","dateModified":"2026-03-14T00:31:40+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lo-stato-del-mare-tabitha-lasley-9788831912068\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lo-stato-del-mare-tabitha-lasley-9788831912068\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lo-stato-del-mare-tabitha-lasley-9788831912068\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lo-stato-del-mare-tabitha-lasley-nr-edizioni-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lo-stato-del-mare-tabitha-lasley-nr-edizioni-1.jpg","width":500,"height":754},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/lo-stato-del-mare-tabitha-lasley-9788831912068\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"lo stato del mare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"18.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788831912068","product_condition":"new"},"df_price":18,"df_sale_price":"","df_regular_price":18,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/lo-stato-del-mare-tabitha-lasley-nr-edizioni-1-199x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/109685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=109685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/144899"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=109685"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=109685"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=109685"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=109685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}