{"id":103811,"date":"2023-07-11T17:19:48","date_gmt":"2023-07-11T15:19:48","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/"},"modified":"2026-03-14T01:44:36","modified_gmt":"2026-03-14T00:44:36","slug":"navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/","title":{"rendered":"navigare con il gommone"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione del Gruppo Ugo Mursia Editore del 1996 in perfetto stato di conservazione. In-16, brossura (con qualche segno del tempo) illustrata a colori; 112 pp.; con 36 illustrazioni in nero nel testo.<\/strong><\/p>\n<p><strong>Disegni tecnici di Manuela De Lorenzi e vignette di Mario Rapetti.<\/strong><\/p>\n<p>Dalla quarta di copertina:&nbsp;<em>Il gommone &egrave; sicuramente il mezzo nautico pi&ugrave; pratico e versatile per poter effettuare della navigazione costiera: ci&ograve; lo ha portato ad essere la barca pi&ugrave; diffusa, in assoluto, nei nostri mari.<\/em><\/p>\n<p><em>In questo libro ci si occupa in particolare dei gommoni cosiddetti semirigidi, quelli dotati di carena in vetroresina. Questi battelli rappresentano infatti la pi&ugrave; moderna evoluzione dei gommoni tradizionali. Con l&#8217;avvento della V.T.R., al gommone si aprono nuovi orizzonti ed esso diventa in breve tempo il mezzo preferito dal&nbsp;<\/em>piccolo diporto<em> e questo perch&eacute; la nuova imbarcazione unisce doti di leggerezza e sicurezza a indubbie qualit&agrave; marine.<\/em><\/p>\n<p><em>I primi modelli non furono altro che l&#8217;unione tra una carena in V.T.R. e una parte pneumatica mentre, con il passare del tempo, le tecniche costruttive si sono via via affinate fornendo un prodotto che ha ormai poco da spartire con i suoi predecessori.<\/em><\/p>\n<p><em>Attraverso questo libro, semplice ed essenziale ma ricco di preziosi consigli e di utili informazioni, il lettore che gi&agrave; naviga sui gommoni, o che si sta avvicinando a questo mezzo, potr&agrave; arricchire e perfezionare la propria esperienza di navigazione migliorando la tecnica e allargando gli orizzonti delle sue rotte.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>scelta, motorizzazione, utilizzo, sicurezza, riparazione e rimessaggio<\/p>\n<p class=\"autore\"><span>Author: <\/span>giovanni bracco &#8211; stefano castiglioni<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788842520535<\/p>\n","protected":false},"featured_media":118219,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2606,2577],"product_tag":[],"class_list":{"0":"post-103811","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-encyclopedias-atlases-and-handbooks","7":"product_cat-books-motorboating-and-marine-engines","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>navigare con il gommone - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"navigare con il gommone\" \/>\n<meta property=\"og:description\" content=\"Subtitle: scelta, motorizzazione, utilizzo, sicurezza, riparazione e rimessaggioAuthor: giovanni bracco - stefano castiglioniPublisher: Ugo Mursia EditoreISBN: 9788842520535\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:44:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/navigare-con-il-gommone-sceta-motorizzazione-utilizzo-sicurezza-riparazione-e-rimessaggio-giovanni-bracco-stefano-castiglioni-mursia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"837\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;12,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\\\/\",\"name\":\"navigare con il gommone - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/navigare-con-il-gommone-sceta-motorizzazione-utilizzo-sicurezza-riparazione-e-rimessaggio-giovanni-bracco-stefano-castiglioni-mursia-1.jpg\",\"datePublished\":\"2023-07-11T15:19:48+00:00\",\"dateModified\":\"2026-03-14T00:44:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/navigare-con-il-gommone-sceta-motorizzazione-utilizzo-sicurezza-riparazione-e-rimessaggio-giovanni-bracco-stefano-castiglioni-mursia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/navigare-con-il-gommone-sceta-motorizzazione-utilizzo-sicurezza-riparazione-e-rimessaggio-giovanni-bracco-stefano-castiglioni-mursia-1.jpg\",\"width\":500,\"height\":837},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"navigare con il gommone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"12.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788842520535\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"navigare con il gommone - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"navigare con il gommone","og_description":"Subtitle: scelta, motorizzazione, utilizzo, sicurezza, riparazione e rimessaggioAuthor: giovanni bracco - stefano castiglioniPublisher: Ugo Mursia EditoreISBN: 9788842520535","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:44:36+00:00","og_image":[{"width":500,"height":837,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/navigare-con-il-gommone-sceta-motorizzazione-utilizzo-sicurezza-riparazione-e-rimessaggio-giovanni-bracco-stefano-castiglioni-mursia-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;12,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/","name":"navigare con il gommone - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/navigare-con-il-gommone-sceta-motorizzazione-utilizzo-sicurezza-riparazione-e-rimessaggio-giovanni-bracco-stefano-castiglioni-mursia-1.jpg","datePublished":"2023-07-11T15:19:48+00:00","dateModified":"2026-03-14T00:44:36+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/navigare-con-il-gommone-sceta-motorizzazione-utilizzo-sicurezza-riparazione-e-rimessaggio-giovanni-bracco-stefano-castiglioni-mursia-1.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/navigare-con-il-gommone-sceta-motorizzazione-utilizzo-sicurezza-riparazione-e-rimessaggio-giovanni-bracco-stefano-castiglioni-mursia-1.jpg","width":500,"height":837},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/navigare-con-il-gommone-giovanni-bracco-stefano-castiglioni-9788842520535\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"navigare con il gommone"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"12.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788842520535","product_condition":"new"},"df_price":12,"df_sale_price":"","df_regular_price":12,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/navigare-con-il-gommone-sceta-motorizzazione-utilizzo-sicurezza-riparazione-e-rimessaggio-giovanni-bracco-stefano-castiglioni-mursia-1-179x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/103811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=103811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/118219"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=103811"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=103811"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=103811"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=103811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}