{"id":103810,"date":"2023-07-11T17:46:19","date_gmt":"2023-07-11T15:46:19","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/"},"modified":"2026-03-14T01:44:34","modified_gmt":"2026-03-14T00:44:34","slug":"piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378","status":"publish","type":"product","link":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/","title":{"rendered":"piccolo manuale di navigazione da diporto"},"content":{"rendered":"<p><strong>Raro esemplare della seconda edizione di U. Mursia &amp; C. del 1970 in perfetto stato di conservazione, collana &ldquo;Biblioteca del Mare&rdquo; 1 (Manuali, tecnica e sport 1). In-16, brossura in similpelle blu, con impressioni oro al piatto anteriore e al dorso; con sovraccoperta in carta plastificata illustrata a colori con alette (con segni del tempo ai tagli); 184 pp. (ingiallite), con 113 illustrazioni in nero nel testo.<\/strong><\/p>\n<p><strong>Con prefazione di Beppe Croce, appendice di Mario Bini e volantino promozionale coevo.<\/strong><\/p>\n<p>Dall&#8217;aletta anteriore:&nbsp;<em>Fino ad oggi non esisteva un&nbsp;<\/em>Manuale&nbsp;<em>di facile consultazione, chiaro, preciso e sintetico, che trattasse tutti i problemi del diporto nautico da un punto di vista eminentemente pratico e in forma semplice e piacevolmente discorsiva. L&#8217;Autrice del nostro volume (che ha gi&agrave; al suo attivo numerose crociere e regate ed ha pubblicato in Inghilterra alcuni volumi sulla navigazione da diporto riscuotendo larghi successi di lettori e di critica) ha raggiunto pienamente lo scopo; questo&nbsp;<\/em>Piccolo manuale di navigazione da diporto<em> &egrave; infatti un vero e proprio&nbsp;<\/em>vademecum<em> per gli&nbsp;<\/em>yachtsmen<em>, tanto per gli esperti quanto per quelli alle prime armi, perch&eacute; d&agrave; in breve e con chiarezza tutte le notizie necessarie a condurre una barca per mare. Quali sono i libri e gli strumenti da avere sotto mano, come comportarsi praticamente nelle pi&ugrave; svariate circostanze, come fare il punto, come procedere di notte e con scarsa visibilit&agrave;, come usare la&nbsp;<\/em>navigazione stimata<em>: a questi e ad altri numerosi interrogativi risponde il&nbsp;<\/em>Manuale&nbsp;<em>di Mary Blewitt, oltre che in modo esauriente e semplice,&nbsp;<\/em>con una levit&agrave;<em>, &egrave; stato detto,&nbsp;<\/em>da far ricordare, in qualche pagina, il miglior Hemingway de&nbsp;<em>Il vecchio e il mare<\/em><em>. La comprensione del testo &egrave; facilitata dai numerosi disegni che evidenziano maggiormente i punti pi&ugrave; complessi.<\/em><\/p>\n<p><em>L&#8217;opera &egrave; corredata da un&#8217;Appendice del Capitano di Vascello Mario Bini sulle deviazioni della bussola, che per la prima volta tratta in maniera piana e senza termini complicati un argomento, possiamo dire,&nbsp;<\/em>quasi inaccessibile&nbsp;<em>ai non esperti, cos&igrave; da metterlo veramente alla portata di tutti.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>mary blewitt<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1689090378<\/p>\n","protected":false},"featured_media":137839,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2606,2578],"product_tag":[],"class_list":{"0":"post-103810","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-encyclopedias-atlases-and-handbooks","7":"product_cat-books-sailing-cruising-and-regatta","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>piccolo manuale di navigazione da diporto - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"piccolo manuale di navigazione da diporto\" \/>\n<meta property=\"og:description\" content=\"Author: mary blewittPublisher: Ugo Mursia EditoreISBN: LDM1689090378\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-14T00:44:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-mursia-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"776\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\\\/\",\"name\":\"piccolo manuale di navigazione da diporto - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-mursia-2.jpg\",\"datePublished\":\"2023-07-11T15:46:19+00:00\",\"dateModified\":\"2026-03-14T00:44:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-mursia-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-mursia-2.jpg\",\"width\":500,\"height\":776},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"piccolo manuale di navigazione da diporto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.sernicola-labs.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"15.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1689090378\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"piccolo manuale di navigazione da diporto - Libreria del Mare","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"piccolo manuale di navigazione da diporto","og_description":"Author: mary blewittPublisher: Ugo Mursia EditoreISBN: LDM1689090378","og_url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-03-14T00:44:34+00:00","og_image":[{"width":500,"height":776,"url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-mursia-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;15,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/","name":"piccolo manuale di navigazione da diporto - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-mursia-2.jpg","datePublished":"2023-07-11T15:46:19+00:00","dateModified":"2026-03-14T00:44:34+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/#primaryimage","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-mursia-2.jpg","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-mursia-2.jpg","width":500,"height":776},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-ldm1689090378\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"piccolo manuale di navigazione da diporto"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#website","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.sernicola-labs.it\/diritto-di-recesso\/"}}]},"product_price_amount":"15.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1689090378","product_condition":"new"},"df_price":15,"df_sale_price":"","df_regular_price":15,"df_image_link":"https:\/\/libreriadelmare.sernicola-labs.it\/wp-content\/uploads\/piccolo-manuale-di-navigazione-da-diporto-mary-blewitt-mursia-2-193x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product\/103810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/comments?post=103810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media\/137839"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/media?parent=103810"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_brand?post=103810"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_cat?post=103810"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.sernicola-labs.it\/en\/wp-json\/wp\/v2\/product_tag?post=103810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}